{"id":20673,"date":"2026-05-25T18:27:28","date_gmt":"2026-05-25T16:27:28","guid":{"rendered":"https:\/\/www.kirche-sdh.de\/side\/?p=20673"},"modified":"2026-05-25T18:27:28","modified_gmt":"2026-05-25T16:27:28","slug":"ein-gottesdienst-fuer-alle","status":"publish","type":"post","link":"https:\/\/www.kirche-sdh.de\/side\/ein-gottesdienst-fuer-alle\/","title":{"rendered":"Ein Gottesdienst f\u00fcr alle"},"content":{"rendered":"<p><strong>Inklusiver Gottesdienst mit Geb\u00e4rdensprachchor \u201cDie singenden H\u00e4nde\u201c beendet 31. unBehinderten Kulturtage<\/strong><\/p>\n<p><strong>Sch\u00f6nthal<\/strong>. Mit einem bunten Gottesdienst in der Sch\u00f6nthaler Pfarrkirche Sankt Michael sind die 31. unBehinderten Kulturtage des Landkreis Cham zu Ende gegangen. Viele Besucher fanden sich zum gemeinsamen Abschluss ein und setzten damit ein Zeichen f\u00fcr gelebte Gemeinschaft und Inklusion, \u201eMenschen unabh\u00e4ngig von Einschr\u00e4nkungen zusammenzubringen und Gemeinschaft erlebbar zu machen.\u201c<\/p>\n<p>Eine besondere Bereicherung des Gottesdienstes waren die \u201eSingenden H\u00e4nde\u201c unter Leitung von Martha Pilsl, die mit ihren eindrucksvollen Darbietungen f\u00fcr bewegende Momente sorgten. Durch die Verbindung von Musik und Geb\u00e4rden gelang es dem Chor aus Geh\u00f6rlosen und Schwerh\u00f6rigen, die Botschaft der Lieder auf besondere Weise f\u00fcr alle erlebbar zu machen. Zelebriert wurde die Gottesdienstfeier von Ortspfarrer Alfons Eder und Behindertenseelsorger in der Di\u00f6zese Regensburg, Pfarrer Christian Burkhardt, der in die Geb\u00e4rdensprache \u00fcbersetzte.<\/p>\n<p>Auch die Mitfeiernden selbst waren eingeladen aktiv an der Gestaltung mitzuwirken und die Bewegungen und Geb\u00e4rden mitzumachen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5883.jpg\" alt=\"\" width=\"2000\" height=\"1333\" class=\"alignnone size-full wp-image-20674\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5883.jpg 2000w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5883-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5883-1024x682.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5883-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5883-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5883-360x240.jpg 360w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/> \u00a0<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5909.jpg\" alt=\"\" width=\"2000\" height=\"1333\" class=\"alignnone size-full wp-image-20676\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5909.jpg 2000w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5909-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5909-1024x682.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5909-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5909-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5909-360x240.jpg 360w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p>\u201eDie Welt ist bunt und farbenfroh, wie ein Regenbogen\u201c f\u00fchrte Pfarrer Eder zusammen mit Kindern anhand farbiger T\u00fccher vor Augen. \u201eSo bunt und farbenfroh wie ein Regenboden, so unterschiedlich sind auch die Menschen.\u201c In diesen Unterschieden seien sie in der Gottesdienstfeier aber eine gro\u00dfe Gemeinschaft, die Gott lobt und dankt.<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5887.jpg\" alt=\"\" width=\"2000\" height=\"1333\" class=\"alignnone size-full wp-image-20675\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5887.jpg 2000w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5887-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5887-1024x682.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5887-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5887-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5887-360x240.jpg 360w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p>Zum Ende dankte Pfarrer Alfons Eder den Verantwortlichen allen Mitwirkenden, Helfern und Besuchern, die zum Gelingen des Gottesdienstes beigetragen haben, allen voran den \u201eSingenden H\u00e4nden\u201c. Ihnen spendeten die Besucher langanhaltenden Applaus, der mit einer Zugabe belohnt wurde.<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5916.jpg\" alt=\"\" width=\"2000\" height=\"1333\" class=\"alignnone size-full wp-image-20677\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5916.jpg 2000w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5916-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5916-1024x682.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5916-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5916-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5916-360x240.jpg 360w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inklusiver Gottesdienst mit Geb\u00e4rdensprachchor \u201cDie singenden H\u00e4nde\u201c beendet 31. unBehinderten Kulturtage Sch\u00f6nthal. Mit einem bunten Gottesdienst in der Sch\u00f6nthaler Pfarrkirche Sankt Michael sind die 31. unBehinderten Kulturtage des Landkreis Cham zu Ende gegangen. Viele Besucher fanden sich zum gemeinsamen Abschluss ein und setzten damit ein Zeichen f\u00fcr gelebte Gemeinschaft und [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":20674,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-20673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schoenthal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ein Gottesdienst f\u00fcr alle - Informationsseite und Seelsorgeeinheit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-sdh.de\/side\/ein-gottesdienst-fuer-alle\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ein Gottesdienst f\u00fcr alle - Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"og:description\" content=\"Inklusiver Gottesdienst mit Geb\u00e4rdensprachchor \u201cDie singenden H\u00e4nde\u201c beendet 31. unBehinderten Kulturtage Sch\u00f6nthal. Mit einem bunten Gottesdienst in der Sch\u00f6nthaler Pfarrkirche Sankt Michael sind die 31. unBehinderten Kulturtage des Landkreis Cham zu Ende gegangen. Viele Besucher fanden sich zum gemeinsamen Abschluss ein und setzten damit ein Zeichen f\u00fcr gelebte Gemeinschaft und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-sdh.de\/side\/ein-gottesdienst-fuer-alle\/\" \/>\n<meta property=\"og:site_name\" content=\"Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-25T16:27:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5883.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin Zangl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Zangl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/ein-gottesdienst-fuer-alle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/ein-gottesdienst-fuer-alle\\\/\"},\"author\":{\"name\":\"Martin Zangl\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/e05baeb81583d4659c11ea77b24c3640\"},\"headline\":\"Ein Gottesdienst f\u00fcr alle\",\"datePublished\":\"2026-05-25T16:27:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/ein-gottesdienst-fuer-alle\\\/\"},\"wordCount\":260,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/ein-gottesdienst-fuer-alle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/IMG_5883.jpg\",\"articleSection\":[\"Sch\u00f6nthal\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/ein-gottesdienst-fuer-alle\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/ein-gottesdienst-fuer-alle\\\/\",\"name\":\"Ein Gottesdienst f\u00fcr alle - Informationsseite und Seelsorgeeinheit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/ein-gottesdienst-fuer-alle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/ein-gottesdienst-fuer-alle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/IMG_5883.jpg\",\"datePublished\":\"2026-05-25T16:27:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/ein-gottesdienst-fuer-alle\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/ein-gottesdienst-fuer-alle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/ein-gottesdienst-fuer-alle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/IMG_5883.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/IMG_5883.jpg\",\"width\":2000,\"height\":1333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/ein-gottesdienst-fuer-alle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ein Gottesdienst f\u00fcr alle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"description\":\"Informationsseite und Seelsorgeeinheit\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"width\":438,\"height\":191,\"caption\":\"Informationsseite und Seelsorgeeinheit\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/e05baeb81583d4659c11ea77b24c3640\",\"name\":\"Martin Zangl\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/author\\\/zangl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ein Gottesdienst f\u00fcr alle - Informationsseite und Seelsorgeeinheit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-sdh.de\/side\/ein-gottesdienst-fuer-alle\/","og_locale":"de_DE","og_type":"article","og_title":"Ein Gottesdienst f\u00fcr alle - Informationsseite und Seelsorgeeinheit","og_description":"Inklusiver Gottesdienst mit Geb\u00e4rdensprachchor \u201cDie singenden H\u00e4nde\u201c beendet 31. unBehinderten Kulturtage Sch\u00f6nthal. Mit einem bunten Gottesdienst in der Sch\u00f6nthaler Pfarrkirche Sankt Michael sind die 31. unBehinderten Kulturtage des Landkreis Cham zu Ende gegangen. Viele Besucher fanden sich zum gemeinsamen Abschluss ein und setzten damit ein Zeichen f\u00fcr gelebte Gemeinschaft und [&hellip;]","og_url":"https:\/\/www.kirche-sdh.de\/side\/ein-gottesdienst-fuer-alle\/","og_site_name":"Informationsseite und Seelsorgeeinheit","article_published_time":"2026-05-25T16:27:28+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5883.jpg","type":"image\/jpeg"}],"author":"Martin Zangl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Martin Zangl","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kirche-sdh.de\/side\/ein-gottesdienst-fuer-alle\/#article","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/ein-gottesdienst-fuer-alle\/"},"author":{"name":"Martin Zangl","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/e05baeb81583d4659c11ea77b24c3640"},"headline":"Ein Gottesdienst f\u00fcr alle","datePublished":"2026-05-25T16:27:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/ein-gottesdienst-fuer-alle\/"},"wordCount":260,"publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/ein-gottesdienst-fuer-alle\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5883.jpg","articleSection":["Sch\u00f6nthal"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kirche-sdh.de\/side\/ein-gottesdienst-fuer-alle\/","url":"https:\/\/www.kirche-sdh.de\/side\/ein-gottesdienst-fuer-alle\/","name":"Ein Gottesdienst f\u00fcr alle - Informationsseite und Seelsorgeeinheit","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/ein-gottesdienst-fuer-alle\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/ein-gottesdienst-fuer-alle\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5883.jpg","datePublished":"2026-05-25T16:27:28+00:00","breadcrumb":{"@id":"https:\/\/www.kirche-sdh.de\/side\/ein-gottesdienst-fuer-alle\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-sdh.de\/side\/ein-gottesdienst-fuer-alle\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/ein-gottesdienst-fuer-alle\/#primaryimage","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5883.jpg","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_5883.jpg","width":2000,"height":1333},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-sdh.de\/side\/ein-gottesdienst-fuer-alle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-sdh.de\/side\/"},{"@type":"ListItem","position":2,"name":"Ein Gottesdienst f\u00fcr alle"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-sdh.de\/side\/#website","url":"https:\/\/www.kirche-sdh.de\/side\/","name":"Informationsseite und Seelsorgeeinheit","description":"Informationsseite und Seelsorgeeinheit","publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-sdh.de\/side\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.kirche-sdh.de\/side\/#organization","name":"Informationsseite und Seelsorgeeinheit","url":"https:\/\/www.kirche-sdh.de\/side\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","width":438,"height":191,"caption":"Informationsseite und Seelsorgeeinheit"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/e05baeb81583d4659c11ea77b24c3640","name":"Martin Zangl","url":"https:\/\/www.kirche-sdh.de\/side\/author\/zangl\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/20673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/comments?post=20673"}],"version-history":[{"count":0,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/20673\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media\/20674"}],"wp:attachment":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media?parent=20673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/categories?post=20673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/tags?post=20673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}