{"id":20152,"date":"2025-09-23T19:39:34","date_gmt":"2025-09-23T17:39:34","guid":{"rendered":"https:\/\/www.kirche-sdh.de\/side\/?p=20152"},"modified":"2025-09-23T19:40:00","modified_gmt":"2025-09-23T17:40:00","slug":"anmeldung-zur-firmung-2026-ab-sofort-moeglich","status":"publish","type":"post","link":"https:\/\/www.kirche-sdh.de\/side\/anmeldung-zur-firmung-2026-ab-sofort-moeglich\/","title":{"rendered":"Anmeldung zur Firmung 2026 ab sofort m\u00f6glich"},"content":{"rendered":"<p><strong><em>Pfarreiengemeinschaft Sch\u00f6nthal &#8211; D\u00f6fering &#8211; Hiltersried<\/em><\/strong><\/p>\n<p><strong><em>Firmung 2026<\/em><\/strong><br \/>\n<em>Zur Firmung 2026 k\u00f6nnen sich die Sch\u00fclerinnen und Sch\u00fcler der 5. und 6. Klassen anmelden. Die Anmeldeformulare k\u00f6nnen ab sofort im Pfarrb\u00fcro in Sch\u00f6nthal zu den B\u00fcrozeiten (Donnerstag 16.00 bis 18.00 Uhr) abgeholt werden. <\/em><br \/>\n<em>Die Anmeldungen bitte bis Ende Oktober ausgef\u00fcllt im Pfarrb\u00fcro wieder abgeben. Die Firmung findet in R\u00f6tz statt. Der Termin wird sobald er bekannt ist, im Pfarrbrief ver\u00f6ffentlicht.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pfarreiengemeinschaft Sch\u00f6nthal &#8211; D\u00f6fering &#8211; Hiltersried Firmung 2026 Zur Firmung 2026 k\u00f6nnen sich die Sch\u00fclerinnen und Sch\u00fcler der 5. und 6. Klassen anmelden. Die Anmeldeformulare k\u00f6nnen ab sofort im Pfarrb\u00fcro in Sch\u00f6nthal zu den B\u00fcrozeiten (Donnerstag 16.00 bis 18.00 Uhr) abgeholt werden. Die Anmeldungen bitte bis Ende Oktober ausgef\u00fcllt im [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,19,21,51],"tags":[],"class_list":["post-20152","post","type-post","status-publish","format-standard","hentry","category-doefering","category-hiltersried","category-schoenthal","category-schoenthal-doefering-hiltersried"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anmeldung zur Firmung 2026 ab sofort m\u00f6glich - Informationsseite und Seelsorgeeinheit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-sdh.de\/side\/anmeldung-zur-firmung-2026-ab-sofort-moeglich\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anmeldung zur Firmung 2026 ab sofort m\u00f6glich - Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"og:description\" content=\"Pfarreiengemeinschaft Sch\u00f6nthal &#8211; D\u00f6fering &#8211; Hiltersried Firmung 2026 Zur Firmung 2026 k\u00f6nnen sich die Sch\u00fclerinnen und Sch\u00fcler der 5. und 6. Klassen anmelden. Die Anmeldeformulare k\u00f6nnen ab sofort im Pfarrb\u00fcro in Sch\u00f6nthal zu den B\u00fcrozeiten (Donnerstag 16.00 bis 18.00 Uhr) abgeholt werden. Die Anmeldungen bitte bis Ende Oktober ausgef\u00fcllt im [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-sdh.de\/side\/anmeldung-zur-firmung-2026-ab-sofort-moeglich\/\" \/>\n<meta property=\"og:site_name\" content=\"Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-23T17:39:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-23T17:40:00+00:00\" \/>\n<meta name=\"author\" content=\"Dirscherl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dirscherl\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/anmeldung-zur-firmung-2026-ab-sofort-moeglich\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/anmeldung-zur-firmung-2026-ab-sofort-moeglich\\\/\"},\"author\":{\"name\":\"Dirscherl\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/03813c96da9249c1923a325c77818b1a\"},\"headline\":\"Anmeldung zur Firmung 2026 ab sofort m\u00f6glich\",\"datePublished\":\"2025-09-23T17:39:34+00:00\",\"dateModified\":\"2025-09-23T17:40:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/anmeldung-zur-firmung-2026-ab-sofort-moeglich\\\/\"},\"wordCount\":83,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"articleSection\":[\"D\u00f6fering\",\"Hiltersried\",\"Sch\u00f6nthal\",\"Sch\u00f6nthal\\\/D\u00f6fering\\\/Hiltersried\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/anmeldung-zur-firmung-2026-ab-sofort-moeglich\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/anmeldung-zur-firmung-2026-ab-sofort-moeglich\\\/\",\"name\":\"Anmeldung zur Firmung 2026 ab sofort m\u00f6glich - Informationsseite und Seelsorgeeinheit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\"},\"datePublished\":\"2025-09-23T17:39:34+00:00\",\"dateModified\":\"2025-09-23T17:40:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/anmeldung-zur-firmung-2026-ab-sofort-moeglich\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/anmeldung-zur-firmung-2026-ab-sofort-moeglich\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/anmeldung-zur-firmung-2026-ab-sofort-moeglich\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anmeldung zur Firmung 2026 ab sofort m\u00f6glich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"description\":\"Informationsseite und Seelsorgeeinheit\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"width\":438,\"height\":191,\"caption\":\"Informationsseite und Seelsorgeeinheit\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/03813c96da9249c1923a325c77818b1a\",\"name\":\"Dirscherl\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/author\\\/kirchesdh\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anmeldung zur Firmung 2026 ab sofort m\u00f6glich - Informationsseite und Seelsorgeeinheit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-sdh.de\/side\/anmeldung-zur-firmung-2026-ab-sofort-moeglich\/","og_locale":"de_DE","og_type":"article","og_title":"Anmeldung zur Firmung 2026 ab sofort m\u00f6glich - Informationsseite und Seelsorgeeinheit","og_description":"Pfarreiengemeinschaft Sch\u00f6nthal &#8211; D\u00f6fering &#8211; Hiltersried Firmung 2026 Zur Firmung 2026 k\u00f6nnen sich die Sch\u00fclerinnen und Sch\u00fcler der 5. und 6. Klassen anmelden. Die Anmeldeformulare k\u00f6nnen ab sofort im Pfarrb\u00fcro in Sch\u00f6nthal zu den B\u00fcrozeiten (Donnerstag 16.00 bis 18.00 Uhr) abgeholt werden. Die Anmeldungen bitte bis Ende Oktober ausgef\u00fcllt im [&hellip;]","og_url":"https:\/\/www.kirche-sdh.de\/side\/anmeldung-zur-firmung-2026-ab-sofort-moeglich\/","og_site_name":"Informationsseite und Seelsorgeeinheit","article_published_time":"2025-09-23T17:39:34+00:00","article_modified_time":"2025-09-23T17:40:00+00:00","author":"Dirscherl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Dirscherl"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kirche-sdh.de\/side\/anmeldung-zur-firmung-2026-ab-sofort-moeglich\/#article","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/anmeldung-zur-firmung-2026-ab-sofort-moeglich\/"},"author":{"name":"Dirscherl","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/03813c96da9249c1923a325c77818b1a"},"headline":"Anmeldung zur Firmung 2026 ab sofort m\u00f6glich","datePublished":"2025-09-23T17:39:34+00:00","dateModified":"2025-09-23T17:40:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/anmeldung-zur-firmung-2026-ab-sofort-moeglich\/"},"wordCount":83,"publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"articleSection":["D\u00f6fering","Hiltersried","Sch\u00f6nthal","Sch\u00f6nthal\/D\u00f6fering\/Hiltersried"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kirche-sdh.de\/side\/anmeldung-zur-firmung-2026-ab-sofort-moeglich\/","url":"https:\/\/www.kirche-sdh.de\/side\/anmeldung-zur-firmung-2026-ab-sofort-moeglich\/","name":"Anmeldung zur Firmung 2026 ab sofort m\u00f6glich - Informationsseite und Seelsorgeeinheit","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#website"},"datePublished":"2025-09-23T17:39:34+00:00","dateModified":"2025-09-23T17:40:00+00:00","breadcrumb":{"@id":"https:\/\/www.kirche-sdh.de\/side\/anmeldung-zur-firmung-2026-ab-sofort-moeglich\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-sdh.de\/side\/anmeldung-zur-firmung-2026-ab-sofort-moeglich\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-sdh.de\/side\/anmeldung-zur-firmung-2026-ab-sofort-moeglich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-sdh.de\/side\/"},{"@type":"ListItem","position":2,"name":"Anmeldung zur Firmung 2026 ab sofort m\u00f6glich"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-sdh.de\/side\/#website","url":"https:\/\/www.kirche-sdh.de\/side\/","name":"Informationsseite und Seelsorgeeinheit","description":"Informationsseite und Seelsorgeeinheit","publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-sdh.de\/side\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.kirche-sdh.de\/side\/#organization","name":"Informationsseite und Seelsorgeeinheit","url":"https:\/\/www.kirche-sdh.de\/side\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","width":438,"height":191,"caption":"Informationsseite und Seelsorgeeinheit"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/03813c96da9249c1923a325c77818b1a","name":"Dirscherl","url":"https:\/\/www.kirche-sdh.de\/side\/author\/kirchesdh\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/20152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/comments?post=20152"}],"version-history":[{"count":0,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/20152\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media?parent=20152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/categories?post=20152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/tags?post=20152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}