{"id":20067,"date":"2025-06-16T13:52:52","date_gmt":"2025-06-16T11:52:52","guid":{"rendered":"https:\/\/www.kirche-sdh.de\/side\/?p=20067"},"modified":"2025-06-16T13:52:52","modified_gmt":"2025-06-16T11:52:52","slug":"konvent-der-mmc","status":"publish","type":"post","link":"https:\/\/www.kirche-sdh.de\/side\/konvent-der-mmc\/","title":{"rendered":"Konvent der MMC"},"content":{"rendered":"<p><strong>Gemeinsamer Konvent der MMC in D\u00f6fering<\/strong><o:p><\/o:p><\/p>\n<p>Am vergangenen Sonntag fand nach dem Gottesdienst im D\u00f6feringer Pfarrheim der gemeinsame Konvent der Kongregationen aus Sch\u00f6nthal, D\u00f6fering und Hiltersried statt. Dazu hatten die Obm\u00e4nner Wolfgang Kumschier (D\u00f6fering, 72 Mitglieder), Maximilian Ruhland (Sch\u00f6nthal, 65 Mitglieder) und Michael R\u00f6tzer (Hiltersried, 19 Mitglieder) eingeladen.<o:p><\/o:p><\/p>\n<p>Die Obm\u00e4nner berichteten, dass man in Bezug auf die Mitgliederzahlen leider von der Substanz lebe und dass an Wachstum nicht zu denken sei. Anschlie\u00dfend gedachte man der seit dem letzten Konvent verstorbenen Mitglieder:<o:p><\/o:p><\/p>\n<p><strong>D\u00f6fering:<\/strong> Ludwig Dirnberger, Max Rohrm\u00fcller; <strong>Sch\u00f6nthal:<\/strong> Alois Schmid; <strong>Hiltersried:<\/strong> Willibald Niebauer, Siegfried Decker, Josef Stautner<o:p><\/o:p><\/p>\n<p><strong>Folgende Mitglieder wurden geehrt:<\/strong> <em>D\u00f6fering:<\/em> <strong>50 Jahre:<\/strong> Hans Zwicknagl, Mathias Wutz, Georg Unverzart, Franz R\u00f6tzer, Karl Malterer <strong>40 Jahre:<\/strong> Georg Wutz, Josef Stautner, Josef Maier, Gerhard Dirnberger <strong>25 Jahre:<\/strong> Johann Kisyma, Rainer Wutz, Markus Daschner<o:p><\/o:p><\/p>\n<p><em>Sch\u00f6nthal:<\/em> <strong>50 Jahre:<\/strong> Erich Dobmeier, Franz Beer<o:p><\/o:p><\/p>\n<p>Pfarrer Alfons Eder gab anschlie\u00dfend Impulse als Grundlage f\u00fcr eine rege Diskussion \u00fcber den Zustand der katholischen Kirche. Obwohl immer wieder Ver\u00e4nderungsprozesse angesto\u00dfen werden (z. B. der Synodale Weg), tut sich die Kirche schwer mit praktischen Erneuerungen. Eine besondere Herausforderung sei es, den kleinsten gemeinsamen Nenner in der Weltkirche zu finden, da es auf den verschiedenen Kontinenten viele unterschiedliche Str\u00f6mungen gebe.<o:p><\/o:p><\/p>\n<p>Gerade die Erfahrungen aus der Lutherisierung w\u00e4hrend der Reformation h\u00e4tten gezeigt, dass es ohne Deutungshoheit (wenn \u201ejeder Papst ist\u201c) schnell zu Abspaltungen kommen k\u00f6nne. Dem Papst komme daher die Aufgabe zu, Ver\u00e4nderungsw\u00fcnsche bis zu einem allgemeing\u00fcltigen Konsens zu entwickeln.<o:p><\/o:p><\/p>\n<p>Themen wie Frauen in Weihe\u00e4mtern kommen dabei leider zu kurz, obwohl gerade Frauen aus der Kirche nicht wegzudenken sind. Auf den liberalen Papst Franziskus folgte zuletzt mit Papst Leo ein Oberhaupt, das eine Mischung aus Tradition und Moderne verk\u00f6rpert und sich offen sowie volksnah zeigt. Daher ruhen auf ihm die Hoffnungen, den Synodalen Weg auch in Zukunft fortzuf\u00fchren.<o:p><\/o:p><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1004287-1024x683.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-20068\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1004287-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1004287-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1004287-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1004287-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1004287-360x240.jpg 360w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1004287.jpg 1600w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1004296-1024x682.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-20069\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1004296-1024x682.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1004296-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1004296-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1004296-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1004296-360x240.jpg 360w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1004296.jpg 2000w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gemeinsamer Konvent der MMC in D\u00f6fering Am vergangenen Sonntag fand nach dem Gottesdienst im D\u00f6feringer Pfarrheim der gemeinsame Konvent der Kongregationen aus Sch\u00f6nthal, D\u00f6fering und Hiltersried statt. Dazu hatten die Obm\u00e4nner Wolfgang Kumschier (D\u00f6fering, 72 Mitglieder), Maximilian Ruhland (Sch\u00f6nthal, 65 Mitglieder) und Michael R\u00f6tzer (Hiltersried, 19 Mitglieder) eingeladen. Die Obm\u00e4nner [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20068,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,19,21,51],"tags":[],"class_list":["post-20067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-doefering","category-hiltersried","category-schoenthal","category-schoenthal-doefering-hiltersried"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Konvent der MMC - Informationsseite und Seelsorgeeinheit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-sdh.de\/side\/konvent-der-mmc\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Konvent der MMC - Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"og:description\" content=\"Gemeinsamer Konvent der MMC in D\u00f6fering Am vergangenen Sonntag fand nach dem Gottesdienst im D\u00f6feringer Pfarrheim der gemeinsame Konvent der Kongregationen aus Sch\u00f6nthal, D\u00f6fering und Hiltersried statt. Dazu hatten die Obm\u00e4nner Wolfgang Kumschier (D\u00f6fering, 72 Mitglieder), Maximilian Ruhland (Sch\u00f6nthal, 65 Mitglieder) und Michael R\u00f6tzer (Hiltersried, 19 Mitglieder) eingeladen. Die Obm\u00e4nner [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-sdh.de\/side\/konvent-der-mmc\/\" \/>\n<meta property=\"og:site_name\" content=\"Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-16T11:52:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1004287.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dirscherl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dirscherl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/konvent-der-mmc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/konvent-der-mmc\\\/\"},\"author\":{\"name\":\"Dirscherl\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/03813c96da9249c1923a325c77818b1a\"},\"headline\":\"Konvent der MMC\",\"datePublished\":\"2025-06-16T11:52:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/konvent-der-mmc\\\/\"},\"wordCount\":324,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/konvent-der-mmc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/P1004287.jpg\",\"articleSection\":[\"D\u00f6fering\",\"Hiltersried\",\"Sch\u00f6nthal\",\"Sch\u00f6nthal\\\/D\u00f6fering\\\/Hiltersried\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/konvent-der-mmc\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/konvent-der-mmc\\\/\",\"name\":\"Konvent der MMC - Informationsseite und Seelsorgeeinheit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/konvent-der-mmc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/konvent-der-mmc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/P1004287.jpg\",\"datePublished\":\"2025-06-16T11:52:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/konvent-der-mmc\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/konvent-der-mmc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/konvent-der-mmc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/P1004287.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/P1004287.jpg\",\"width\":1600,\"height\":1067},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/konvent-der-mmc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Konvent der MMC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"description\":\"Informationsseite und Seelsorgeeinheit\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"width\":438,\"height\":191,\"caption\":\"Informationsseite und Seelsorgeeinheit\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/03813c96da9249c1923a325c77818b1a\",\"name\":\"Dirscherl\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/author\\\/kirchesdh\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Konvent der MMC - Informationsseite und Seelsorgeeinheit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-sdh.de\/side\/konvent-der-mmc\/","og_locale":"de_DE","og_type":"article","og_title":"Konvent der MMC - Informationsseite und Seelsorgeeinheit","og_description":"Gemeinsamer Konvent der MMC in D\u00f6fering Am vergangenen Sonntag fand nach dem Gottesdienst im D\u00f6feringer Pfarrheim der gemeinsame Konvent der Kongregationen aus Sch\u00f6nthal, D\u00f6fering und Hiltersried statt. Dazu hatten die Obm\u00e4nner Wolfgang Kumschier (D\u00f6fering, 72 Mitglieder), Maximilian Ruhland (Sch\u00f6nthal, 65 Mitglieder) und Michael R\u00f6tzer (Hiltersried, 19 Mitglieder) eingeladen. Die Obm\u00e4nner [&hellip;]","og_url":"https:\/\/www.kirche-sdh.de\/side\/konvent-der-mmc\/","og_site_name":"Informationsseite und Seelsorgeeinheit","article_published_time":"2025-06-16T11:52:52+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1004287.jpg","type":"image\/jpeg"}],"author":"Dirscherl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Dirscherl","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kirche-sdh.de\/side\/konvent-der-mmc\/#article","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/konvent-der-mmc\/"},"author":{"name":"Dirscherl","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/03813c96da9249c1923a325c77818b1a"},"headline":"Konvent der MMC","datePublished":"2025-06-16T11:52:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/konvent-der-mmc\/"},"wordCount":324,"publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/konvent-der-mmc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1004287.jpg","articleSection":["D\u00f6fering","Hiltersried","Sch\u00f6nthal","Sch\u00f6nthal\/D\u00f6fering\/Hiltersried"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kirche-sdh.de\/side\/konvent-der-mmc\/","url":"https:\/\/www.kirche-sdh.de\/side\/konvent-der-mmc\/","name":"Konvent der MMC - Informationsseite und Seelsorgeeinheit","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/konvent-der-mmc\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/konvent-der-mmc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1004287.jpg","datePublished":"2025-06-16T11:52:52+00:00","breadcrumb":{"@id":"https:\/\/www.kirche-sdh.de\/side\/konvent-der-mmc\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-sdh.de\/side\/konvent-der-mmc\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/konvent-der-mmc\/#primaryimage","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1004287.jpg","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1004287.jpg","width":1600,"height":1067},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-sdh.de\/side\/konvent-der-mmc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-sdh.de\/side\/"},{"@type":"ListItem","position":2,"name":"Konvent der MMC"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-sdh.de\/side\/#website","url":"https:\/\/www.kirche-sdh.de\/side\/","name":"Informationsseite und Seelsorgeeinheit","description":"Informationsseite und Seelsorgeeinheit","publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-sdh.de\/side\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.kirche-sdh.de\/side\/#organization","name":"Informationsseite und Seelsorgeeinheit","url":"https:\/\/www.kirche-sdh.de\/side\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","width":438,"height":191,"caption":"Informationsseite und Seelsorgeeinheit"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/03813c96da9249c1923a325c77818b1a","name":"Dirscherl","url":"https:\/\/www.kirche-sdh.de\/side\/author\/kirchesdh\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/20067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/comments?post=20067"}],"version-history":[{"count":0,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/20067\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media\/20068"}],"wp:attachment":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media?parent=20067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/categories?post=20067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/tags?post=20067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}