{"id":19993,"date":"2025-04-28T14:20:46","date_gmt":"2025-04-28T12:20:46","guid":{"rendered":"https:\/\/www.kirche-sdh.de\/side\/?p=19993"},"modified":"2025-04-28T14:20:46","modified_gmt":"2025-04-28T12:20:46","slug":"mia-magdalena-boesl-in-doefering-getauft","status":"publish","type":"post","link":"https:\/\/www.kirche-sdh.de\/side\/mia-magdalena-boesl-in-doefering-getauft\/","title":{"rendered":"Mia Magdalena B\u00f6sl in D\u00f6fering getauft"},"content":{"rendered":"<p><strong>Mia Magdalena B\u00f6sl in D\u00f6fering getauft<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003925-1024x683.jpg\" alt=\"\" width=\"608\" height=\"405\" class=\"alignnone  wp-image-19999\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003925-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003925-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003925-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003925-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003925-360x240.jpg 360w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003925.jpg 1600w\" sizes=\"auto, (max-width: 608px) 100vw, 608px\" \/><\/p>\n<p>Am vergangenen Sonntag begr\u00fc\u00dfte Glockengel\u00e4ut die Taufgemeinschaft, welche sich im Eingangsbereich der Pfarrkirche St. \u00c4gidius anl\u00e4\u00dflich der Taufe von Mia Magdalena B\u00f6sl versammelt hatte. Mia ist Tochter der Eheleute Thomas und Lisa B\u00f6sl aus D\u00f6fering.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003891-1024x683.jpg\" alt=\"\" width=\"620\" height=\"413\" class=\"alignnone  wp-image-19994\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003891-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003891-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003891-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003891-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003891-360x240.jpg 360w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003891.jpg 1600w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><br \/>\nEs ist sch\u00f6n, dass die gesunde Mia aus der Verwandtschaft mit gleichaltrigen aufwachsen kann, da dieses eine Bereicherung alle Kinder darstellt, so Pfarrer Alfons Eder bei der Begr\u00fc\u00dfung. Gerne wurde der Bitte der Eltern nach der Taufe von Mia entsprochen.<br \/>\nDie kleine Mia soll am Vorbild der Eltern und der Patin Magdalena Bindl das Beten lernen und einen Platz in der Kirche bekommen. Zum Segen zeichneten die Anwesenden Mia ein Kreuz auf die Stirn.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003893-683x1024.jpg\" alt=\"\" width=\"554\" height=\"831\" class=\"alignnone  wp-image-19995\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003893-683x1024.jpg 683w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003893-200x300.jpg 200w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003893-768x1152.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003893-1024x1536.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003893.jpg 1067w\" sizes=\"auto, (max-width: 554px) 100vw, 554px\" \/><br \/>\nNach der Lesung nach Markus (Wer das Reich Gottes nicht annimmt wie ein Kind) richtete Pfarrer Eder seine pers\u00f6nlichen Worte an die Anwesenden. Vor kurzem hatte er in der Zeitung einen Artikel zu Namen von prominenten Kindern gelesen. Besonders stechen dabei die drei Kinder von Tesla Chef Elon Musk mit der Kanadierin Grimes hervor: X \u00c6 A-Xii (genannt: X), Exa Dark Sider\u00e6l (genannt: Y) und Techno Mechanicus (genannt: Tau)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003899-1024x683.jpg\" alt=\"\" width=\"600\" height=\"400\" class=\"alignnone  wp-image-19996\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003899-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003899-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003899-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003899-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003899-360x240.jpg 360w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003899.jpg 1600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><br \/>\nDer durch die Eheleute B\u00f6sl gew\u00e4hlte Name Mia ist hier deutlich einfacher und sch\u00f6ner!<br \/>\nMia ist dabei eine Variation von Maria und hat die Bedeutung Meerstern. Zum zweiten Namen Magdalena f\u00fchrte er aus, dass diese die treueste J\u00fcngerin bis unters Kreuz von Jesus war. Mia hat damit zwei starke Frauen als Namenspatroninnen. Bei der Taufe kommt mit Christin noch ein zus\u00e4tzlicher, ehrenvoller Name hinzu. Der Familienname verbindet uns mit Mama und Papa wogegen der Vorname f\u00fcr die Pers\u00f6nlichkeit steht. Kinder sind bei Jesus herzlich willkommen.<br \/>\nMusikalisch wurde die Tauffeier durch Lissa Laubmeier, Rita B\u00f6sl, Hildegard Mauerer sowie an der Gitarre durch Stephanie Schlosser umrahmt.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003914-1024x683.jpg\" alt=\"\" width=\"590\" height=\"393\" class=\"alignnone  wp-image-19998\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003914-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003914-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003914-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003914-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003914-360x240.jpg 360w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003914.jpg 1600w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/><br \/>\nNachdem sich die Anwesenden am Taufbecken versammelt hatten legten Eltern und die Taufpatin stellvertretend f\u00fcr Mia das Taufversprechen ab. Danach wurde Mia mit heiligem Wasser getauft und mit Chrisam gesalbt. Die Taufkerze wurde an der Osterkerze entz\u00fcndet. Mit dem Effata Ruf wurde darum gebeten, dass Gott bei Ohren und den Mund \u00f6ffnen wolle.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003904-1024x683.jpg\" alt=\"\" width=\"638\" height=\"425\" class=\"alignnone  wp-image-19997\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003904-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003904-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003904-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003904-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003904-360x240.jpg 360w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003904.jpg 1600w\" sizes=\"auto, (max-width: 638px) 100vw, 638px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mia Magdalena B\u00f6sl in D\u00f6fering getauft &nbsp; Am vergangenen Sonntag begr\u00fc\u00dfte Glockengel\u00e4ut die Taufgemeinschaft, welche sich im Eingangsbereich der Pfarrkirche St. \u00c4gidius anl\u00e4\u00dflich der Taufe von Mia Magdalena B\u00f6sl versammelt hatte. Mia ist Tochter der Eheleute Thomas und Lisa B\u00f6sl aus D\u00f6fering. Es ist sch\u00f6n, dass die gesunde Mia aus [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19999,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-19993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-doefering"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mia Magdalena B\u00f6sl in D\u00f6fering getauft - Informationsseite und Seelsorgeeinheit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-sdh.de\/side\/mia-magdalena-boesl-in-doefering-getauft\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mia Magdalena B\u00f6sl in D\u00f6fering getauft - Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"og:description\" content=\"Mia Magdalena B\u00f6sl in D\u00f6fering getauft &nbsp; Am vergangenen Sonntag begr\u00fc\u00dfte Glockengel\u00e4ut die Taufgemeinschaft, welche sich im Eingangsbereich der Pfarrkirche St. \u00c4gidius anl\u00e4\u00dflich der Taufe von Mia Magdalena B\u00f6sl versammelt hatte. Mia ist Tochter der Eheleute Thomas und Lisa B\u00f6sl aus D\u00f6fering. Es ist sch\u00f6n, dass die gesunde Mia aus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-sdh.de\/side\/mia-magdalena-boesl-in-doefering-getauft\/\" \/>\n<meta property=\"og:site_name\" content=\"Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-28T12:20:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003925.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dirscherl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dirscherl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/mia-magdalena-boesl-in-doefering-getauft\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/mia-magdalena-boesl-in-doefering-getauft\\\/\"},\"author\":{\"name\":\"Dirscherl\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/03813c96da9249c1923a325c77818b1a\"},\"headline\":\"Mia Magdalena B\u00f6sl in D\u00f6fering getauft\",\"datePublished\":\"2025-04-28T12:20:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/mia-magdalena-boesl-in-doefering-getauft\\\/\"},\"wordCount\":372,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/mia-magdalena-boesl-in-doefering-getauft\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/P1003925.jpg\",\"articleSection\":[\"D\u00f6fering\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/mia-magdalena-boesl-in-doefering-getauft\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/mia-magdalena-boesl-in-doefering-getauft\\\/\",\"name\":\"Mia Magdalena B\u00f6sl in D\u00f6fering getauft - Informationsseite und Seelsorgeeinheit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/mia-magdalena-boesl-in-doefering-getauft\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/mia-magdalena-boesl-in-doefering-getauft\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/P1003925.jpg\",\"datePublished\":\"2025-04-28T12:20:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/mia-magdalena-boesl-in-doefering-getauft\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/mia-magdalena-boesl-in-doefering-getauft\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/mia-magdalena-boesl-in-doefering-getauft\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/P1003925.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/P1003925.jpg\",\"width\":1600,\"height\":1067},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/mia-magdalena-boesl-in-doefering-getauft\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mia Magdalena B\u00f6sl in D\u00f6fering getauft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"description\":\"Informationsseite und Seelsorgeeinheit\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"width\":438,\"height\":191,\"caption\":\"Informationsseite und Seelsorgeeinheit\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/03813c96da9249c1923a325c77818b1a\",\"name\":\"Dirscherl\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/author\\\/kirchesdh\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mia Magdalena B\u00f6sl in D\u00f6fering getauft - Informationsseite und Seelsorgeeinheit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-sdh.de\/side\/mia-magdalena-boesl-in-doefering-getauft\/","og_locale":"de_DE","og_type":"article","og_title":"Mia Magdalena B\u00f6sl in D\u00f6fering getauft - Informationsseite und Seelsorgeeinheit","og_description":"Mia Magdalena B\u00f6sl in D\u00f6fering getauft &nbsp; Am vergangenen Sonntag begr\u00fc\u00dfte Glockengel\u00e4ut die Taufgemeinschaft, welche sich im Eingangsbereich der Pfarrkirche St. \u00c4gidius anl\u00e4\u00dflich der Taufe von Mia Magdalena B\u00f6sl versammelt hatte. Mia ist Tochter der Eheleute Thomas und Lisa B\u00f6sl aus D\u00f6fering. Es ist sch\u00f6n, dass die gesunde Mia aus [&hellip;]","og_url":"https:\/\/www.kirche-sdh.de\/side\/mia-magdalena-boesl-in-doefering-getauft\/","og_site_name":"Informationsseite und Seelsorgeeinheit","article_published_time":"2025-04-28T12:20:46+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003925.jpg","type":"image\/jpeg"}],"author":"Dirscherl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Dirscherl","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kirche-sdh.de\/side\/mia-magdalena-boesl-in-doefering-getauft\/#article","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/mia-magdalena-boesl-in-doefering-getauft\/"},"author":{"name":"Dirscherl","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/03813c96da9249c1923a325c77818b1a"},"headline":"Mia Magdalena B\u00f6sl in D\u00f6fering getauft","datePublished":"2025-04-28T12:20:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/mia-magdalena-boesl-in-doefering-getauft\/"},"wordCount":372,"publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/mia-magdalena-boesl-in-doefering-getauft\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003925.jpg","articleSection":["D\u00f6fering"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kirche-sdh.de\/side\/mia-magdalena-boesl-in-doefering-getauft\/","url":"https:\/\/www.kirche-sdh.de\/side\/mia-magdalena-boesl-in-doefering-getauft\/","name":"Mia Magdalena B\u00f6sl in D\u00f6fering getauft - Informationsseite und Seelsorgeeinheit","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/mia-magdalena-boesl-in-doefering-getauft\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/mia-magdalena-boesl-in-doefering-getauft\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003925.jpg","datePublished":"2025-04-28T12:20:46+00:00","breadcrumb":{"@id":"https:\/\/www.kirche-sdh.de\/side\/mia-magdalena-boesl-in-doefering-getauft\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-sdh.de\/side\/mia-magdalena-boesl-in-doefering-getauft\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/mia-magdalena-boesl-in-doefering-getauft\/#primaryimage","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003925.jpg","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003925.jpg","width":1600,"height":1067},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-sdh.de\/side\/mia-magdalena-boesl-in-doefering-getauft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-sdh.de\/side\/"},{"@type":"ListItem","position":2,"name":"Mia Magdalena B\u00f6sl in D\u00f6fering getauft"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-sdh.de\/side\/#website","url":"https:\/\/www.kirche-sdh.de\/side\/","name":"Informationsseite und Seelsorgeeinheit","description":"Informationsseite und Seelsorgeeinheit","publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-sdh.de\/side\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.kirche-sdh.de\/side\/#organization","name":"Informationsseite und Seelsorgeeinheit","url":"https:\/\/www.kirche-sdh.de\/side\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","width":438,"height":191,"caption":"Informationsseite und Seelsorgeeinheit"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/03813c96da9249c1923a325c77818b1a","name":"Dirscherl","url":"https:\/\/www.kirche-sdh.de\/side\/author\/kirchesdh\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/19993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/comments?post=19993"}],"version-history":[{"count":0,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/19993\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media\/19999"}],"wp:attachment":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media?parent=19993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/categories?post=19993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/tags?post=19993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}