{"id":19966,"date":"2025-04-18T10:25:09","date_gmt":"2025-04-18T08:25:09","guid":{"rendered":"https:\/\/www.kirche-sdh.de\/side\/?p=19966"},"modified":"2025-04-18T10:25:09","modified_gmt":"2025-04-18T08:25:09","slug":"pfarrgarten-aus-winterschlaf-geholt","status":"publish","type":"post","link":"https:\/\/www.kirche-sdh.de\/side\/pfarrgarten-aus-winterschlaf-geholt\/","title":{"rendered":"Pfarrgarten aus Winterschlaf geholt"},"content":{"rendered":"<p><strong>OGV und Pfarrei packen an \u2013 Str\u00e4ucher und Rosen wurden geschnitten, Fenster geputzt<\/strong><\/p>\n<p><strong>Sch\u00f6nthal<\/strong>. In einer gemeinsamen j\u00e4hrlichen Aktion haben Mitglieder des \u00f6rtlichen Vereins f\u00fcr Gartenbau und Landespflege, des Pfarrgemeinderates, der Kirchenverwaltung, der Frauengemeinschaft und einige freiwillige Helfer die Hinterlassenschaften des Winters im Pfarrgarten und rund um die Pfarrkirche beseitigt. Dar\u00fcber hinaus wurden die zahlreichen Fenster im Pfarr- und Jugendheim durch die Mutter-Kind-Gruppe, das B\u00fcchereiteam und Helferinnen auf Hochglanz geputzt. Die OGV-Vorsitzende Rosmarie Bauer konnte sich wie gewohnt auf ihre Mitglieder verlassen, ebenso wie Pfarrgemeinderatssprecher Maximilian Ruhland und Kirchenpfleger Martin Zangl. Str\u00e4ucher und Rosen wurden geschnitten, Vertrocknetes entfernt, Unkraut gezupft und Rindenmulch auf die Rabatten verteilt. Der Austausch von Gartenwissen und Gartenweisheiten zur Ausbreitung des Giersch oder des Buchsbaumz\u00fcnslers kamen dabei nicht zu kurz. Nach getaner Arbeit wurde der Einsatz mit einer Brotzeit sowie Kaffee und Kuchen beendet und die Gartenabf\u00e4lle entsorgt.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_115629-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" class=\"alignnone size-full wp-image-19967\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_115629-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_115629-300x225.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_115629-1024x768.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_115629-768x576.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_115629-1536x1152.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_115629-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_121645-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" class=\"alignnone size-full wp-image-19968\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_121645-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_121645-300x225.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_121645-1024x768.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_121645-768x576.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_121645-1536x1152.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_121645-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_113614-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" class=\"alignnone size-full wp-image-19973\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_113614-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_113614-300x225.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_113614-1024x768.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_113614-768x576.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_113614-1536x1152.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_113614-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_113819-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" class=\"alignnone size-full wp-image-19974\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_113819-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_113819-300x225.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_113819-1024x768.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_113819-768x576.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_113819-1536x1152.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_113819-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_115648-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" class=\"alignnone size-full wp-image-19975\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_115648-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_115648-300x225.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_115648-1024x768.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_115648-768x576.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_115648-1536x1152.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_115648-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_122624-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" class=\"alignnone size-full wp-image-19976\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_122624-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_122624-300x225.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_122624-1024x768.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_122624-768x576.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_122624-1536x1152.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_122624-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180944-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" class=\"alignnone size-full wp-image-19972\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180944-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180944-300x225.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180944-1024x768.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180944-768x576.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180944-1536x1152.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180944-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180928-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" class=\"alignnone size-full wp-image-19971\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180928-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180928-300x225.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180928-1024x768.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180928-768x576.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180928-1536x1152.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180928-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180832-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" class=\"alignnone size-full wp-image-19970\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180832-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180832-300x225.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180832-1024x768.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180832-768x576.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180832-1536x1152.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180832-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_171025-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" class=\"alignnone size-full wp-image-19969\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_171025-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_171025-300x225.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_171025-1024x768.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_171025-768x576.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_171025-1536x1152.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_171025-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>OGV und Pfarrei packen an \u2013 Str\u00e4ucher und Rosen wurden geschnitten, Fenster geputzt Sch\u00f6nthal. In einer gemeinsamen j\u00e4hrlichen Aktion haben Mitglieder des \u00f6rtlichen Vereins f\u00fcr Gartenbau und Landespflege, des Pfarrgemeinderates, der Kirchenverwaltung, der Frauengemeinschaft und einige freiwillige Helfer die Hinterlassenschaften des Winters im Pfarrgarten und rund um die Pfarrkirche beseitigt. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":19970,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-19966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schoenthal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pfarrgarten aus Winterschlaf geholt - Informationsseite und Seelsorgeeinheit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-sdh.de\/side\/pfarrgarten-aus-winterschlaf-geholt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pfarrgarten aus Winterschlaf geholt - Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"og:description\" content=\"OGV und Pfarrei packen an \u2013 Str\u00e4ucher und Rosen wurden geschnitten, Fenster geputzt Sch\u00f6nthal. In einer gemeinsamen j\u00e4hrlichen Aktion haben Mitglieder des \u00f6rtlichen Vereins f\u00fcr Gartenbau und Landespflege, des Pfarrgemeinderates, der Kirchenverwaltung, der Frauengemeinschaft und einige freiwillige Helfer die Hinterlassenschaften des Winters im Pfarrgarten und rund um die Pfarrkirche beseitigt. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-sdh.de\/side\/pfarrgarten-aus-winterschlaf-geholt\/\" \/>\n<meta property=\"og:site_name\" content=\"Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-18T08:25:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180832-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin Zangl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Zangl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/pfarrgarten-aus-winterschlaf-geholt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/pfarrgarten-aus-winterschlaf-geholt\\\/\"},\"author\":{\"name\":\"Martin Zangl\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/e05baeb81583d4659c11ea77b24c3640\"},\"headline\":\"Pfarrgarten aus Winterschlaf geholt\",\"datePublished\":\"2025-04-18T08:25:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/pfarrgarten-aus-winterschlaf-geholt\\\/\"},\"wordCount\":155,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/pfarrgarten-aus-winterschlaf-geholt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/20250412_180832-scaled.jpg\",\"articleSection\":[\"Sch\u00f6nthal\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/pfarrgarten-aus-winterschlaf-geholt\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/pfarrgarten-aus-winterschlaf-geholt\\\/\",\"name\":\"Pfarrgarten aus Winterschlaf geholt - Informationsseite und Seelsorgeeinheit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/pfarrgarten-aus-winterschlaf-geholt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/pfarrgarten-aus-winterschlaf-geholt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/20250412_180832-scaled.jpg\",\"datePublished\":\"2025-04-18T08:25:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/pfarrgarten-aus-winterschlaf-geholt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/pfarrgarten-aus-winterschlaf-geholt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/pfarrgarten-aus-winterschlaf-geholt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/20250412_180832-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/20250412_180832-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/pfarrgarten-aus-winterschlaf-geholt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pfarrgarten aus Winterschlaf geholt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"description\":\"Informationsseite und Seelsorgeeinheit\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"width\":438,\"height\":191,\"caption\":\"Informationsseite und Seelsorgeeinheit\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/e05baeb81583d4659c11ea77b24c3640\",\"name\":\"Martin Zangl\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/author\\\/zangl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pfarrgarten aus Winterschlaf geholt - Informationsseite und Seelsorgeeinheit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-sdh.de\/side\/pfarrgarten-aus-winterschlaf-geholt\/","og_locale":"de_DE","og_type":"article","og_title":"Pfarrgarten aus Winterschlaf geholt - Informationsseite und Seelsorgeeinheit","og_description":"OGV und Pfarrei packen an \u2013 Str\u00e4ucher und Rosen wurden geschnitten, Fenster geputzt Sch\u00f6nthal. In einer gemeinsamen j\u00e4hrlichen Aktion haben Mitglieder des \u00f6rtlichen Vereins f\u00fcr Gartenbau und Landespflege, des Pfarrgemeinderates, der Kirchenverwaltung, der Frauengemeinschaft und einige freiwillige Helfer die Hinterlassenschaften des Winters im Pfarrgarten und rund um die Pfarrkirche beseitigt. [&hellip;]","og_url":"https:\/\/www.kirche-sdh.de\/side\/pfarrgarten-aus-winterschlaf-geholt\/","og_site_name":"Informationsseite und Seelsorgeeinheit","article_published_time":"2025-04-18T08:25:09+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180832-scaled.jpg","type":"image\/jpeg"}],"author":"Martin Zangl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Martin Zangl","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kirche-sdh.de\/side\/pfarrgarten-aus-winterschlaf-geholt\/#article","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/pfarrgarten-aus-winterschlaf-geholt\/"},"author":{"name":"Martin Zangl","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/e05baeb81583d4659c11ea77b24c3640"},"headline":"Pfarrgarten aus Winterschlaf geholt","datePublished":"2025-04-18T08:25:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/pfarrgarten-aus-winterschlaf-geholt\/"},"wordCount":155,"publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/pfarrgarten-aus-winterschlaf-geholt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180832-scaled.jpg","articleSection":["Sch\u00f6nthal"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kirche-sdh.de\/side\/pfarrgarten-aus-winterschlaf-geholt\/","url":"https:\/\/www.kirche-sdh.de\/side\/pfarrgarten-aus-winterschlaf-geholt\/","name":"Pfarrgarten aus Winterschlaf geholt - Informationsseite und Seelsorgeeinheit","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/pfarrgarten-aus-winterschlaf-geholt\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/pfarrgarten-aus-winterschlaf-geholt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180832-scaled.jpg","datePublished":"2025-04-18T08:25:09+00:00","breadcrumb":{"@id":"https:\/\/www.kirche-sdh.de\/side\/pfarrgarten-aus-winterschlaf-geholt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-sdh.de\/side\/pfarrgarten-aus-winterschlaf-geholt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/pfarrgarten-aus-winterschlaf-geholt\/#primaryimage","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180832-scaled.jpg","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20250412_180832-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-sdh.de\/side\/pfarrgarten-aus-winterschlaf-geholt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-sdh.de\/side\/"},{"@type":"ListItem","position":2,"name":"Pfarrgarten aus Winterschlaf geholt"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-sdh.de\/side\/#website","url":"https:\/\/www.kirche-sdh.de\/side\/","name":"Informationsseite und Seelsorgeeinheit","description":"Informationsseite und Seelsorgeeinheit","publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-sdh.de\/side\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.kirche-sdh.de\/side\/#organization","name":"Informationsseite und Seelsorgeeinheit","url":"https:\/\/www.kirche-sdh.de\/side\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","width":438,"height":191,"caption":"Informationsseite und Seelsorgeeinheit"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/e05baeb81583d4659c11ea77b24c3640","name":"Martin Zangl","url":"https:\/\/www.kirche-sdh.de\/side\/author\/zangl\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/19966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/comments?post=19966"}],"version-history":[{"count":0,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/19966\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media\/19970"}],"wp:attachment":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media?parent=19966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/categories?post=19966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/tags?post=19966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}