{"id":19863,"date":"2025-02-16T11:14:47","date_gmt":"2025-02-16T10:14:47","guid":{"rendered":"https:\/\/www.kirche-sdh.de\/side\/?p=19863"},"modified":"2025-02-16T11:14:47","modified_gmt":"2025-02-16T10:14:47","slug":"von-der-taufe-zur-kommunion","status":"publish","type":"post","link":"https:\/\/www.kirche-sdh.de\/side\/von-der-taufe-zur-kommunion\/","title":{"rendered":"Von der Taufe zur Kommunion"},"content":{"rendered":"<p><strong>Kommunionkinder stellen sich der Pfarrei vor &#8211; am 4. Mai Erstkommunionfeier<\/strong><\/p>\n<p><strong>Sch\u00f6nthal<\/strong>. Drei Jungen und ein M\u00e4dchen der Pfarrei Sch\u00f6nthal werden in diesem Jahr ihre erste heilige Kommunion feiern. Pfarrer Alfons Eder begr\u00fc\u00dfte die Kommunionkinder zu Beginn des Vorabendgottesdienstes und hie\u00df sie herzlich mit ihren Eltern, Gro\u00dfeltern und Geschwistern willkommen. Die Kinder stellten sich der Pfarrgemeinde, in deren Mahlgemeinschaft sie gemeinsam mit den D\u00f6feringer Kommunionkindern am 4. Mai in D\u00f6fering aufgenommen werden, pers\u00f6nlich vor und erneuerten das Glaubensbekenntnis.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4242-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1569\" class=\"alignnone size-full wp-image-19865\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4242-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4242-300x184.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4242-1024x628.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4242-768x471.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4242-1536x941.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4242-2048x1255.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p>Mit der Vorstellung in der Pfarrei und dem Empfang der ersten heiligen Kommunion w\u00fcrden die Kinder wieder ein St\u00fcckchen mehr zur Pfarrei geh\u00f6ren, f\u00fchrte Gemeindereferentin Rosa-Maria Roth aus. In der Taufe habe das Dazugeh\u00f6ren begonnen als die Eltern entschieden, dass die Kinder ein Teil dieser Kirche werden sollten. Die Eltern h\u00e4tten damals stellvertretend die Zustimmung und das Glaubensbekenntnis gesprochen. Heute w\u00e4ren die Kinder an der Reihe, dieses Bekenntnis zur Kirche zu erneuern und zu wiederholen. Sie w\u00fcrden damit den Bogen von ihrer Taufe zur Erstkommunion spannen und h\u00e4tten deshalb ihre Taufkerzen mitgebracht. Pfarrer Eder rief die Kommunionkinder an den Altar, wo er sie namentlich vorstellte.\u00a0Die Kinder bezeugten ihren Glauben, bekreuzigten sich mit Weihwasser und entz\u00fcndeten ihre auf dem Altar aufgereihten Taufkerzen an der Osterkerze.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4245-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" class=\"alignnone size-full wp-image-19866\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4245-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4245-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4245-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4245-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4245-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4245-2048x1365.jpg 2048w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4245-360x240.jpg 360w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p>Das Glaubensbekenntnis der Kinder bekr\u00e4ftige die Pfarrgemeinde mit ihrem Bekenntnis. Damit w\u00fcrden die Gl\u00e4ubigen Vorbild f\u00fcr die Kinder sein. Als Zeichen f\u00fcr ihren Glauben erhielten die Kommunionkinder von ihren Eltern ein zuvor gesegnetes Bronzekreuz umgeh\u00e4ngt.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4244-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" class=\"alignnone size-full wp-image-19864\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4244-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4244-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4244-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4244-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4244-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4244-2048x1365.jpg 2048w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4244-360x240.jpg 360w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p>Namentlich empfangen die erste heilige Kommunion Hermine Horn, Sebastian Mauerer, Louis Niezgodka und Benjamin Sch\u00fctz.<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4249-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1720\" class=\"alignnone size-full wp-image-19867\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4249-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4249-300x202.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4249-1024x688.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4249-768x516.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4249-1536x1032.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4249-2048x1376.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kommunionkinder stellen sich der Pfarrei vor &#8211; am 4. Mai Erstkommunionfeier Sch\u00f6nthal. Drei Jungen und ein M\u00e4dchen der Pfarrei Sch\u00f6nthal werden in diesem Jahr ihre erste heilige Kommunion feiern. Pfarrer Alfons Eder begr\u00fc\u00dfte die Kommunionkinder zu Beginn des Vorabendgottesdienstes und hie\u00df sie herzlich mit ihren Eltern, Gro\u00dfeltern und Geschwistern willkommen. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":19865,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-19863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schoenthal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Von der Taufe zur Kommunion - Informationsseite und Seelsorgeeinheit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-sdh.de\/side\/von-der-taufe-zur-kommunion\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Von der Taufe zur Kommunion - Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"og:description\" content=\"Kommunionkinder stellen sich der Pfarrei vor &#8211; am 4. Mai Erstkommunionfeier Sch\u00f6nthal. Drei Jungen und ein M\u00e4dchen der Pfarrei Sch\u00f6nthal werden in diesem Jahr ihre erste heilige Kommunion feiern. Pfarrer Alfons Eder begr\u00fc\u00dfte die Kommunionkinder zu Beginn des Vorabendgottesdienstes und hie\u00df sie herzlich mit ihren Eltern, Gro\u00dfeltern und Geschwistern willkommen. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-sdh.de\/side\/von-der-taufe-zur-kommunion\/\" \/>\n<meta property=\"og:site_name\" content=\"Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-16T10:14:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4242-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1569\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin Zangl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Zangl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/von-der-taufe-zur-kommunion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/von-der-taufe-zur-kommunion\\\/\"},\"author\":{\"name\":\"Martin Zangl\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/e05baeb81583d4659c11ea77b24c3640\"},\"headline\":\"Von der Taufe zur Kommunion\",\"datePublished\":\"2025-02-16T10:14:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/von-der-taufe-zur-kommunion\\\/\"},\"wordCount\":281,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/von-der-taufe-zur-kommunion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/IMG_4242-scaled.jpg\",\"articleSection\":[\"Sch\u00f6nthal\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/von-der-taufe-zur-kommunion\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/von-der-taufe-zur-kommunion\\\/\",\"name\":\"Von der Taufe zur Kommunion - Informationsseite und Seelsorgeeinheit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/von-der-taufe-zur-kommunion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/von-der-taufe-zur-kommunion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/IMG_4242-scaled.jpg\",\"datePublished\":\"2025-02-16T10:14:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/von-der-taufe-zur-kommunion\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/von-der-taufe-zur-kommunion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/von-der-taufe-zur-kommunion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/IMG_4242-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/IMG_4242-scaled.jpg\",\"width\":2560,\"height\":1569},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/von-der-taufe-zur-kommunion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Von der Taufe zur Kommunion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"description\":\"Informationsseite und Seelsorgeeinheit\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"width\":438,\"height\":191,\"caption\":\"Informationsseite und Seelsorgeeinheit\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/e05baeb81583d4659c11ea77b24c3640\",\"name\":\"Martin Zangl\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/author\\\/zangl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Von der Taufe zur Kommunion - Informationsseite und Seelsorgeeinheit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-sdh.de\/side\/von-der-taufe-zur-kommunion\/","og_locale":"de_DE","og_type":"article","og_title":"Von der Taufe zur Kommunion - Informationsseite und Seelsorgeeinheit","og_description":"Kommunionkinder stellen sich der Pfarrei vor &#8211; am 4. Mai Erstkommunionfeier Sch\u00f6nthal. Drei Jungen und ein M\u00e4dchen der Pfarrei Sch\u00f6nthal werden in diesem Jahr ihre erste heilige Kommunion feiern. Pfarrer Alfons Eder begr\u00fc\u00dfte die Kommunionkinder zu Beginn des Vorabendgottesdienstes und hie\u00df sie herzlich mit ihren Eltern, Gro\u00dfeltern und Geschwistern willkommen. [&hellip;]","og_url":"https:\/\/www.kirche-sdh.de\/side\/von-der-taufe-zur-kommunion\/","og_site_name":"Informationsseite und Seelsorgeeinheit","article_published_time":"2025-02-16T10:14:47+00:00","og_image":[{"width":2560,"height":1569,"url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4242-scaled.jpg","type":"image\/jpeg"}],"author":"Martin Zangl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Martin Zangl","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kirche-sdh.de\/side\/von-der-taufe-zur-kommunion\/#article","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/von-der-taufe-zur-kommunion\/"},"author":{"name":"Martin Zangl","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/e05baeb81583d4659c11ea77b24c3640"},"headline":"Von der Taufe zur Kommunion","datePublished":"2025-02-16T10:14:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/von-der-taufe-zur-kommunion\/"},"wordCount":281,"publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/von-der-taufe-zur-kommunion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4242-scaled.jpg","articleSection":["Sch\u00f6nthal"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kirche-sdh.de\/side\/von-der-taufe-zur-kommunion\/","url":"https:\/\/www.kirche-sdh.de\/side\/von-der-taufe-zur-kommunion\/","name":"Von der Taufe zur Kommunion - Informationsseite und Seelsorgeeinheit","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/von-der-taufe-zur-kommunion\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/von-der-taufe-zur-kommunion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4242-scaled.jpg","datePublished":"2025-02-16T10:14:47+00:00","breadcrumb":{"@id":"https:\/\/www.kirche-sdh.de\/side\/von-der-taufe-zur-kommunion\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-sdh.de\/side\/von-der-taufe-zur-kommunion\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/von-der-taufe-zur-kommunion\/#primaryimage","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4242-scaled.jpg","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_4242-scaled.jpg","width":2560,"height":1569},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-sdh.de\/side\/von-der-taufe-zur-kommunion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-sdh.de\/side\/"},{"@type":"ListItem","position":2,"name":"Von der Taufe zur Kommunion"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-sdh.de\/side\/#website","url":"https:\/\/www.kirche-sdh.de\/side\/","name":"Informationsseite und Seelsorgeeinheit","description":"Informationsseite und Seelsorgeeinheit","publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-sdh.de\/side\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.kirche-sdh.de\/side\/#organization","name":"Informationsseite und Seelsorgeeinheit","url":"https:\/\/www.kirche-sdh.de\/side\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","width":438,"height":191,"caption":"Informationsseite und Seelsorgeeinheit"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/e05baeb81583d4659c11ea77b24c3640","name":"Martin Zangl","url":"https:\/\/www.kirche-sdh.de\/side\/author\/zangl\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/19863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/comments?post=19863"}],"version-history":[{"count":0,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/19863\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media\/19865"}],"wp:attachment":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media?parent=19863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/categories?post=19863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/tags?post=19863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}