{"id":19854,"date":"2025-02-13T09:32:24","date_gmt":"2025-02-13T08:32:24","guid":{"rendered":"https:\/\/www.kirche-sdh.de\/side\/?p=19854"},"modified":"2025-02-28T18:39:43","modified_gmt":"2025-02-28T17:39:43","slug":"jahreshauptversammlung-der-klb-doefering-2","status":"publish","type":"post","link":"https:\/\/www.kirche-sdh.de\/side\/jahreshauptversammlung-der-klb-doefering-2\/","title":{"rendered":"Jahreshauptversammlung der KLB D\u00f6fering"},"content":{"rendered":"<p><strong>Jahreshauptversammlung der KLB D\u00f6fering<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Nachdem es im letzten Jahr einen gro\u00dfen Umbruch in der Vorstandschaft der KLB D\u00f6fering gab, konnten nun die Verantwortlichen nach einem w\u00fcrdigen Gedenkgottesdienst R\u00fcckschau halten. Als Teil der Doppelspitze lie\u00df Christian Piendl das vergangene Jahr Revue passieren.<\/p>\n<p>&nbsp;<\/p>\n<p>Im M\u00e4rz nahm man am Di\u00f6zesanauschu\u00df nach Viehausen und betete den Kreuzweg zur Hussenbierlkapelle. Im Juli fand dann die erste Vorstandschaftssitzung statt und ein gr\u00f6\u00dferer Arbeitseinsatz als man mit der Pfarrei das 100-j\u00e4hrige Bestehen dieser feierte. Im Oktober besichtige man den Strau\u00dfenhof der Fa. Betz in Stamsried. Den Jahresausklang erfolgte dann mit einer Vorstandschaftssitzung, der Aussendung der Marienfiguren dem sog. Frauentragen, das Ausstellen des Christbaumes am Pfarrheim und die Waldweihnacht mit Krippenspiel am Hussenbierl. Piendl freute sich \u00fcber eine harmonische Zusammenarbeit im Vorstandsteam und auch mit zusammen mit den Mitgliedern. Auf den Kassenbericht von Andreas Kumschier erfolgte die Entlastung der Vorstandschaft. Vorstand Christian Piendl gab dann noch einen Ausblick f\u00fcr das aktuelle\u00a0 Jahr:<\/p>\n<p>30.03. \u00a0 15:00 Uhr \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Kreuzweg zur Hussenbierkapelle<\/p>\n<p>01.06.\u00a0\u00a0 13:30 Uhr \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Radlwallfahrt zu verschiedenen Kapellen<\/p>\n<p>02.-03.08 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Fahrt zur den Eiswelten nach Werfen im Raum Salzburg<\/p>\n<p>26.12.\u00a0\u00a0 19:00 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Waldweihnacht an der Hussenbierlkapelle<\/p>\n<p>10.02.2026\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Jahreshauptversammlung 2026<\/p>\n<p>Kassier Andreas Kumschier legte den Anwesenden dann noch die KLB WhatsApp Gruppe f\u00fcr den schnellen Informationsaustausch im Verein ans Herz.<\/p>\n<p>Pfarrer Alfons Eder freute, dass die neue Vorstandschaft schnell Tritt gefasst hat und bedankte sich f\u00fcr die tatkr\u00e4ftige Unterst\u00fctzung beim 100-j\u00e4hrigen Pfarrjubil\u00e4um.<\/p>\n<p>KLB Di\u00f6zesanvorsitzender Max Hastreiter informiert dann zum aktuellen Stand bei der Di\u00f6zese und vom KLB Kreisverband. Das \u00e4ltere Motto \u201eLebe was dich bewegt\u201c ist immer noch aktuell und trifft auf vor allem auch auf die KLB D\u00f6fering zu. Die Punkte daraus wie l\u00e4ndlicher Raum, Blickpunkt Mensch, jung und alt, Spiritualit\u00e4t und Glaube, weltweite Verbindung am Beispiel des Senegals stehen auch f\u00fcr die Werte der D\u00f6feringer.<\/p>\n<p>Es wurde vor zwei Wochen das neue Hilfsprojekt f\u00fcr den Senegal durch das Bundesministerium f\u00fcr Entwicklung genehmigt. Zusammen mit den Di\u00f6zesen Regensburg und Passau wird das bestehende Bienenprojekt nun erg\u00e4nzt durch bessere Vermarktung und neuen Bienenk\u00e4sten.<\/p>\n<p>Auf Kreisebene sind zwei Veranstaltungen geplant: Am 6. April findet eine Stadtf\u00fchrung im benachbarten Doma\u017elice statt. Am 29.06. ist der Evensong in der D\u00f6feringer Pfarrkirche geplant. Dabei wird ein Abendlob mit besonderen Liedern und Texten mit anschlie\u00dfendem gem\u00fctlichem Beisammensein angepeilt. Obwohl das Landvolk politisch nicht aktiv ist, wies Max Hastreiter auf die Aktion \u201eF\u00fcr alle mit Herz und Verstand\u201c bei dem das Landvolk daf\u00fcr eintritt, dass man bei der Wahl die Menschw\u00fcrde und die N\u00e4chstenliebe und den Zusammenhalt im Blick hat. Abschlie\u00dfend erfolgte noch ein Hinweis auf die Radwallfahrt ins Schweizer Fl\u00fceli, welche die KLB Di\u00f6zese Regensburg mit der KLB Kreis Cham ausrichtet. Vom 12-20.08.2025 wird zuerst an der Bernrieder Bruder Klaus Kapelle aufgebrochen und sich dann auf den Weg nach Fl\u00fceli zum Bruder Klaus und zur Dorothee aufgemacht.<\/p>\n<p>Im Anschlu\u00df an die Jahreshauptversammlung konnte der Hormon- und Abnehmexperte Elias Pscheidt f\u00fcr einen Vortrag zum Thema: \u201eEinfach gesund und nachhaltig zum Wunschgewicht, mehr Energie und Wohlbefinden\u201c gewonnen werden.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003474-1024x683.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19855\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003474-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003474-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003474-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003474-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003474-360x240.jpg 360w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003474.jpg 1600w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003485-1024x683.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19856\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003485-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003485-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003485-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003485-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003485-360x240.jpg 360w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003485.jpg 1600w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003489-1024x683.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19857\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003489-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003489-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003489-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003489-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003489-360x240.jpg 360w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003489.jpg 1600w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> \u00a0\u00a0<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003498-1024x683.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19860\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003498-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003498-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003498-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003498-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003498-360x240.jpg 360w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003498.jpg 1600w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Im Anschlu\u00df an die Jahreshauptversammlung konnte der Hormon- und Abnehmexperte Elias Pscheidt f\u00fcr einen Vortrag zum Thema: \u201eEinfach gesund und nachhaltig zum Wunschgewicht, mehr Energie und Wohlbefinden\u201c gewonnen werden.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003502-1024x683.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19891\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003502-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003502-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003502-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003502-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003502-360x240.jpg 360w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003502.jpg 1600w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003519-1024x488.jpg\" alt=\"\" width=\"750\" height=\"357\" class=\"alignnone size-large wp-image-19892\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003519-1024x488.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003519-300x143.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003519-768x366.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003519-1536x732.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003519.jpg 1600w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003524-683x1024.jpg\" alt=\"\" width=\"683\" height=\"1024\" class=\"alignnone size-large wp-image-19893\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003524-683x1024.jpg 683w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003524-200x300.jpg 200w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003524-768x1152.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003524-1024x1536.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003524.jpg 1067w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003530-1024x506.jpg\" alt=\"\" width=\"750\" height=\"371\" class=\"alignnone size-large wp-image-19894\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003530-1024x506.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003530-300x148.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003530-768x380.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003530-1536x759.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003530.jpg 1600w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> \u00a0<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003576-1024x683.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19896\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003576-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003576-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003576-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003576-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003576-360x240.jpg 360w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003576.jpg 1600w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jahreshauptversammlung der KLB D\u00f6fering &nbsp; Nachdem es im letzten Jahr einen gro\u00dfen Umbruch in der Vorstandschaft der KLB D\u00f6fering gab, konnten nun die Verantwortlichen nach einem w\u00fcrdigen Gedenkgottesdienst R\u00fcckschau halten. Als Teil der Doppelspitze lie\u00df Christian Piendl das vergangene Jahr Revue passieren. &nbsp; Im M\u00e4rz nahm man am Di\u00f6zesanauschu\u00df nach [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19860,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-19854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-doefering"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jahreshauptversammlung der KLB D\u00f6fering - Informationsseite und Seelsorgeeinheit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-sdh.de\/side\/jahreshauptversammlung-der-klb-doefering-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jahreshauptversammlung der KLB D\u00f6fering - Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"og:description\" content=\"Jahreshauptversammlung der KLB D\u00f6fering &nbsp; Nachdem es im letzten Jahr einen gro\u00dfen Umbruch in der Vorstandschaft der KLB D\u00f6fering gab, konnten nun die Verantwortlichen nach einem w\u00fcrdigen Gedenkgottesdienst R\u00fcckschau halten. Als Teil der Doppelspitze lie\u00df Christian Piendl das vergangene Jahr Revue passieren. &nbsp; Im M\u00e4rz nahm man am Di\u00f6zesanauschu\u00df nach [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-sdh.de\/side\/jahreshauptversammlung-der-klb-doefering-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-13T08:32:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-28T17:39:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003498.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dirscherl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dirscherl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/jahreshauptversammlung-der-klb-doefering-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/jahreshauptversammlung-der-klb-doefering-2\\\/\"},\"author\":{\"name\":\"Dirscherl\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/03813c96da9249c1923a325c77818b1a\"},\"headline\":\"Jahreshauptversammlung der KLB D\u00f6fering\",\"datePublished\":\"2025-02-13T08:32:24+00:00\",\"dateModified\":\"2025-02-28T17:39:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/jahreshauptversammlung-der-klb-doefering-2\\\/\"},\"wordCount\":560,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/jahreshauptversammlung-der-klb-doefering-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/P1003498.jpg\",\"articleSection\":[\"D\u00f6fering\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/jahreshauptversammlung-der-klb-doefering-2\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/jahreshauptversammlung-der-klb-doefering-2\\\/\",\"name\":\"Jahreshauptversammlung der KLB D\u00f6fering - Informationsseite und Seelsorgeeinheit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/jahreshauptversammlung-der-klb-doefering-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/jahreshauptversammlung-der-klb-doefering-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/P1003498.jpg\",\"datePublished\":\"2025-02-13T08:32:24+00:00\",\"dateModified\":\"2025-02-28T17:39:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/jahreshauptversammlung-der-klb-doefering-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/jahreshauptversammlung-der-klb-doefering-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/jahreshauptversammlung-der-klb-doefering-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/P1003498.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/P1003498.jpg\",\"width\":1600,\"height\":1067},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/jahreshauptversammlung-der-klb-doefering-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jahreshauptversammlung der KLB D\u00f6fering\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"description\":\"Informationsseite und Seelsorgeeinheit\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"width\":438,\"height\":191,\"caption\":\"Informationsseite und Seelsorgeeinheit\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/03813c96da9249c1923a325c77818b1a\",\"name\":\"Dirscherl\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/author\\\/kirchesdh\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jahreshauptversammlung der KLB D\u00f6fering - Informationsseite und Seelsorgeeinheit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-sdh.de\/side\/jahreshauptversammlung-der-klb-doefering-2\/","og_locale":"de_DE","og_type":"article","og_title":"Jahreshauptversammlung der KLB D\u00f6fering - Informationsseite und Seelsorgeeinheit","og_description":"Jahreshauptversammlung der KLB D\u00f6fering &nbsp; Nachdem es im letzten Jahr einen gro\u00dfen Umbruch in der Vorstandschaft der KLB D\u00f6fering gab, konnten nun die Verantwortlichen nach einem w\u00fcrdigen Gedenkgottesdienst R\u00fcckschau halten. Als Teil der Doppelspitze lie\u00df Christian Piendl das vergangene Jahr Revue passieren. &nbsp; Im M\u00e4rz nahm man am Di\u00f6zesanauschu\u00df nach [&hellip;]","og_url":"https:\/\/www.kirche-sdh.de\/side\/jahreshauptversammlung-der-klb-doefering-2\/","og_site_name":"Informationsseite und Seelsorgeeinheit","article_published_time":"2025-02-13T08:32:24+00:00","article_modified_time":"2025-02-28T17:39:43+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003498.jpg","type":"image\/jpeg"}],"author":"Dirscherl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Dirscherl","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kirche-sdh.de\/side\/jahreshauptversammlung-der-klb-doefering-2\/#article","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/jahreshauptversammlung-der-klb-doefering-2\/"},"author":{"name":"Dirscherl","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/03813c96da9249c1923a325c77818b1a"},"headline":"Jahreshauptversammlung der KLB D\u00f6fering","datePublished":"2025-02-13T08:32:24+00:00","dateModified":"2025-02-28T17:39:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/jahreshauptversammlung-der-klb-doefering-2\/"},"wordCount":560,"publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/jahreshauptversammlung-der-klb-doefering-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003498.jpg","articleSection":["D\u00f6fering"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kirche-sdh.de\/side\/jahreshauptversammlung-der-klb-doefering-2\/","url":"https:\/\/www.kirche-sdh.de\/side\/jahreshauptversammlung-der-klb-doefering-2\/","name":"Jahreshauptversammlung der KLB D\u00f6fering - Informationsseite und Seelsorgeeinheit","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/jahreshauptversammlung-der-klb-doefering-2\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/jahreshauptversammlung-der-klb-doefering-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003498.jpg","datePublished":"2025-02-13T08:32:24+00:00","dateModified":"2025-02-28T17:39:43+00:00","breadcrumb":{"@id":"https:\/\/www.kirche-sdh.de\/side\/jahreshauptversammlung-der-klb-doefering-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-sdh.de\/side\/jahreshauptversammlung-der-klb-doefering-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/jahreshauptversammlung-der-klb-doefering-2\/#primaryimage","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003498.jpg","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003498.jpg","width":1600,"height":1067},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-sdh.de\/side\/jahreshauptversammlung-der-klb-doefering-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-sdh.de\/side\/"},{"@type":"ListItem","position":2,"name":"Jahreshauptversammlung der KLB D\u00f6fering"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-sdh.de\/side\/#website","url":"https:\/\/www.kirche-sdh.de\/side\/","name":"Informationsseite und Seelsorgeeinheit","description":"Informationsseite und Seelsorgeeinheit","publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-sdh.de\/side\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.kirche-sdh.de\/side\/#organization","name":"Informationsseite und Seelsorgeeinheit","url":"https:\/\/www.kirche-sdh.de\/side\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","width":438,"height":191,"caption":"Informationsseite und Seelsorgeeinheit"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/03813c96da9249c1923a325c77818b1a","name":"Dirscherl","url":"https:\/\/www.kirche-sdh.de\/side\/author\/kirchesdh\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/19854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/comments?post=19854"}],"version-history":[{"count":0,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/19854\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media\/19860"}],"wp:attachment":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media?parent=19854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/categories?post=19854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/tags?post=19854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}