{"id":19779,"date":"2024-12-25T18:01:50","date_gmt":"2024-12-25T17:01:50","guid":{"rendered":"https:\/\/www.kirche-sdh.de\/side\/?p=19779"},"modified":"2024-12-25T18:01:50","modified_gmt":"2024-12-25T17:01:50","slug":"weihnachten-in-der-pfarrei-doefering","status":"publish","type":"post","link":"https:\/\/www.kirche-sdh.de\/side\/weihnachten-in-der-pfarrei-doefering\/","title":{"rendered":"Weihnachten in der Pfarrei D\u00f6fering"},"content":{"rendered":"<p>Die Pfarrei D\u00f6fering begann die Weihnachtsfeierlichkeiten wieder mit der Kinderkrippenfeier f\u00fcr die Kleinen. Zu Beginn der Feier sagte Pfarrer Alfons Eder, dass die Kinder heute in der Krippenfeier das Evangelium verk\u00fcnden.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003285.jpg\" alt=\"\" width=\"652\" height=\"435\" class=\"alignnone  wp-image-19780\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003285.jpg 800w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003285-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003285-768x513.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003285-360x240.jpg 360w\" sizes=\"auto, (max-width: 652px) 100vw, 652px\" \/><\/p>\n<p>Dann startete das Krippenspiel , welches durch Johanna Kumschier und Maria Schneider vom Pfarrgemeinderat in mehreren Proben in den vergangenen Wochen \u00a0mit den Kindern einstudiert wurde.\u00a0 Musikalisch wurde die Feier durch Lena Dirscherl an der Orgel und Anna Dirscherl an der Geige festlich umrahmt.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003289.jpg\" alt=\"\" width=\"700\" height=\"467\" class=\"alignnone  wp-image-19781\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003289.jpg 800w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003289-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003289-768x513.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003289-360x240.jpg 360w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>Der Engel Gabriel mit einem Stern \u00fcberbrachte Maria die frohe Botschaft, dass sie ein Kind bekommen wird und sie ihm den Namen Jesus geben soll.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003293.jpg\" alt=\"\" width=\"534\" height=\"800\" class=\"alignnone size-full wp-image-19783\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003293.jpg 534w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003293-200x300.jpg 200w\" sizes=\"auto, (max-width: 534px) 100vw, 534px\" \/><\/p>\n<p>Nachdem ein Soldat die Menschen aufforderte sich in Steuerlisten einzutragen machten sich Maria und Josef auf den Weg nach Betlehem.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003296.jpg\" alt=\"\" width=\"800\" height=\"534\" class=\"alignnone size-full wp-image-19784\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003296.jpg 800w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003296-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003296-768x513.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003296-360x240.jpg 360w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Nach einer schwierigen Herbergssuche erblickte das Jesuskind im Stall das Licht der Welt.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003303.jpg\" alt=\"\" width=\"800\" height=\"534\" class=\"alignnone size-full wp-image-19785\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003303.jpg 800w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003303-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003303-768x513.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003303-360x240.jpg 360w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Die schlafenden Hirten wurden durch die Engel geweckt und auf Jesus aufmerksam gemacht und huldigten dem Herrn machten sich auf den Weg zum Erl\u00f6ser und \u00fcberbrachten Ihre Geschenke ehe sie von Maria und Josef begr\u00fc\u00dft wurden. Nach dem gemeinsam gesungenen Lied \u201eStille Nacht\u201c brachen die Kleinen erwartungsvoll nach Hause zur Bescherung auf.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003306.jpg\" alt=\"\" width=\"800\" height=\"534\" class=\"alignnone size-full wp-image-19786\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003306.jpg 800w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003306-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003306-768x513.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003306-360x240.jpg 360w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003308.jpg\" alt=\"\" width=\"800\" height=\"534\" class=\"alignnone size-full wp-image-19787\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003308.jpg 800w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003308-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003308-768x513.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003308-360x240.jpg 360w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003314.jpg\" alt=\"\" width=\"534\" height=\"800\" class=\"alignnone size-full wp-image-19788\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003314.jpg 534w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003314-200x300.jpg 200w\" sizes=\"auto, (max-width: 534px) 100vw, 534px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003315.jpg\" alt=\"\" width=\"800\" height=\"534\" class=\"alignnone size-full wp-image-19789\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003315.jpg 800w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003315-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003315-768x513.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003315-360x240.jpg 360w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003318.jpg\" alt=\"\" width=\"534\" height=\"800\" class=\"alignnone size-full wp-image-19790\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003318.jpg 534w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003318-200x300.jpg 200w\" sizes=\"auto, (max-width: 534px) 100vw, 534px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003323.jpg\" alt=\"\" width=\"800\" height=\"534\" class=\"alignnone size-full wp-image-19791\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003323.jpg 800w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003323-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003323-768x513.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003323-360x240.jpg 360w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Der Festgottesdienst am 1. Weihnachtsfeiertag wurden dann vom D\u00f6feringer Kirchenchor verst\u00e4rkt\u00a0 mit Trompete und Zitter feierlich gestaltet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Pfarrei D\u00f6fering begann die Weihnachtsfeierlichkeiten wieder mit der Kinderkrippenfeier f\u00fcr die Kleinen. Zu Beginn der Feier sagte Pfarrer Alfons Eder, dass die Kinder heute in der Krippenfeier das Evangelium verk\u00fcnden. Dann startete das Krippenspiel , welches durch Johanna Kumschier und Maria Schneider vom Pfarrgemeinderat in mehreren Proben in den [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19791,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-19779","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-doefering"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weihnachten in der Pfarrei D\u00f6fering - Informationsseite und Seelsorgeeinheit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-sdh.de\/side\/weihnachten-in-der-pfarrei-doefering\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weihnachten in der Pfarrei D\u00f6fering - Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"og:description\" content=\"Die Pfarrei D\u00f6fering begann die Weihnachtsfeierlichkeiten wieder mit der Kinderkrippenfeier f\u00fcr die Kleinen. Zu Beginn der Feier sagte Pfarrer Alfons Eder, dass die Kinder heute in der Krippenfeier das Evangelium verk\u00fcnden. Dann startete das Krippenspiel , welches durch Johanna Kumschier und Maria Schneider vom Pfarrgemeinderat in mehreren Proben in den [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-sdh.de\/side\/weihnachten-in-der-pfarrei-doefering\/\" \/>\n<meta property=\"og:site_name\" content=\"Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-25T17:01:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003323.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dirscherl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dirscherl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/weihnachten-in-der-pfarrei-doefering\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/weihnachten-in-der-pfarrei-doefering\\\/\"},\"author\":{\"name\":\"Dirscherl\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/03813c96da9249c1923a325c77818b1a\"},\"headline\":\"Weihnachten in der Pfarrei D\u00f6fering\",\"datePublished\":\"2024-12-25T17:01:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/weihnachten-in-der-pfarrei-doefering\\\/\"},\"wordCount\":213,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/weihnachten-in-der-pfarrei-doefering\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/P1003323.jpg\",\"articleSection\":[\"D\u00f6fering\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/weihnachten-in-der-pfarrei-doefering\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/weihnachten-in-der-pfarrei-doefering\\\/\",\"name\":\"Weihnachten in der Pfarrei D\u00f6fering - Informationsseite und Seelsorgeeinheit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/weihnachten-in-der-pfarrei-doefering\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/weihnachten-in-der-pfarrei-doefering\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/P1003323.jpg\",\"datePublished\":\"2024-12-25T17:01:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/weihnachten-in-der-pfarrei-doefering\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/weihnachten-in-der-pfarrei-doefering\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/weihnachten-in-der-pfarrei-doefering\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/P1003323.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/P1003323.jpg\",\"width\":800,\"height\":534},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/weihnachten-in-der-pfarrei-doefering\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Weihnachten in der Pfarrei D\u00f6fering\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"description\":\"Informationsseite und Seelsorgeeinheit\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"width\":438,\"height\":191,\"caption\":\"Informationsseite und Seelsorgeeinheit\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/03813c96da9249c1923a325c77818b1a\",\"name\":\"Dirscherl\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/author\\\/kirchesdh\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weihnachten in der Pfarrei D\u00f6fering - Informationsseite und Seelsorgeeinheit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-sdh.de\/side\/weihnachten-in-der-pfarrei-doefering\/","og_locale":"de_DE","og_type":"article","og_title":"Weihnachten in der Pfarrei D\u00f6fering - Informationsseite und Seelsorgeeinheit","og_description":"Die Pfarrei D\u00f6fering begann die Weihnachtsfeierlichkeiten wieder mit der Kinderkrippenfeier f\u00fcr die Kleinen. Zu Beginn der Feier sagte Pfarrer Alfons Eder, dass die Kinder heute in der Krippenfeier das Evangelium verk\u00fcnden. Dann startete das Krippenspiel , welches durch Johanna Kumschier und Maria Schneider vom Pfarrgemeinderat in mehreren Proben in den [&hellip;]","og_url":"https:\/\/www.kirche-sdh.de\/side\/weihnachten-in-der-pfarrei-doefering\/","og_site_name":"Informationsseite und Seelsorgeeinheit","article_published_time":"2024-12-25T17:01:50+00:00","og_image":[{"width":800,"height":534,"url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003323.jpg","type":"image\/jpeg"}],"author":"Dirscherl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Dirscherl","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kirche-sdh.de\/side\/weihnachten-in-der-pfarrei-doefering\/#article","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/weihnachten-in-der-pfarrei-doefering\/"},"author":{"name":"Dirscherl","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/03813c96da9249c1923a325c77818b1a"},"headline":"Weihnachten in der Pfarrei D\u00f6fering","datePublished":"2024-12-25T17:01:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/weihnachten-in-der-pfarrei-doefering\/"},"wordCount":213,"publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/weihnachten-in-der-pfarrei-doefering\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003323.jpg","articleSection":["D\u00f6fering"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kirche-sdh.de\/side\/weihnachten-in-der-pfarrei-doefering\/","url":"https:\/\/www.kirche-sdh.de\/side\/weihnachten-in-der-pfarrei-doefering\/","name":"Weihnachten in der Pfarrei D\u00f6fering - Informationsseite und Seelsorgeeinheit","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/weihnachten-in-der-pfarrei-doefering\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/weihnachten-in-der-pfarrei-doefering\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003323.jpg","datePublished":"2024-12-25T17:01:50+00:00","breadcrumb":{"@id":"https:\/\/www.kirche-sdh.de\/side\/weihnachten-in-der-pfarrei-doefering\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-sdh.de\/side\/weihnachten-in-der-pfarrei-doefering\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/weihnachten-in-der-pfarrei-doefering\/#primaryimage","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003323.jpg","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003323.jpg","width":800,"height":534},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-sdh.de\/side\/weihnachten-in-der-pfarrei-doefering\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-sdh.de\/side\/"},{"@type":"ListItem","position":2,"name":"Weihnachten in der Pfarrei D\u00f6fering"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-sdh.de\/side\/#website","url":"https:\/\/www.kirche-sdh.de\/side\/","name":"Informationsseite und Seelsorgeeinheit","description":"Informationsseite und Seelsorgeeinheit","publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-sdh.de\/side\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.kirche-sdh.de\/side\/#organization","name":"Informationsseite und Seelsorgeeinheit","url":"https:\/\/www.kirche-sdh.de\/side\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","width":438,"height":191,"caption":"Informationsseite und Seelsorgeeinheit"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/03813c96da9249c1923a325c77818b1a","name":"Dirscherl","url":"https:\/\/www.kirche-sdh.de\/side\/author\/kirchesdh\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/19779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/comments?post=19779"}],"version-history":[{"count":0,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/19779\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media\/19791"}],"wp:attachment":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media?parent=19779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/categories?post=19779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/tags?post=19779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}