{"id":19527,"date":"2024-07-26T21:10:51","date_gmt":"2024-07-26T19:10:51","guid":{"rendered":"https:\/\/www.kirche-sdh.de\/side\/?p=19527"},"modified":"2024-07-26T21:10:51","modified_gmt":"2024-07-26T19:10:51","slug":"100-jahre-pfarrei-doefering","status":"publish","type":"post","link":"https:\/\/www.kirche-sdh.de\/side\/100-jahre-pfarrei-doefering\/","title":{"rendered":"100 Jahre Pfarrei D\u00f6fering"},"content":{"rendered":"<p><strong>100 Jahre Pfarrei D\u00f6fering<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Mit \u201ejung, aktiv und innovativ\u201c beschrieb B\u00fcrgermeister Ludwig Wallinger die Pfarrei St. \u00c4gidius D\u00f6fering anl\u00e4\u00dflich Ihres 100. Neugr\u00fcndungsfestes und traf damit den Nagel auf den Kopf.<\/strong><\/p>\n<p>Am vergangenen Sonntag feierte die Pfarrei St. \u00c4gidius D\u00f6fering ihren 100-j\u00e4hriges Bestehen als H\u00f6hepunkt eines Jubeljahres als gro\u00dfe Familie mit einem Fest auf dem Kirchplatz. Laut Heimatforscherin Elfriede Dirschedl zeichnete D\u00f6fering seit vielen Jahrhunderten \u00a0vor allem eines aus: Der Zusammenhalt untereinander. So auch diesmal! Nachdem weder Pfarrgemeinderat oder Kirchenverwaltung allein in der Lage gewesen w\u00e4ren ein solches Fest zu stemmen richteten diese \u00a0im Fr\u00fchjahr vorsichtig die Anfrage an die \u00f6rtlichen Vereine mit der Bitte um Unterst\u00fctzung. Schnell war klar, dass auf die Dorfgemeinschaft gez\u00e4hlt werden konnte und so nahm das Fest unter Hilfe von Obst- und Gartenbauverein, Freiwillige Feuerwehr, KLB, Burschenverein, Rhaner Waldkapellenverein und\u00a0\u00a0 KLJB seinen Lauf.<\/p>\n<p>Am Festtag versammelte sich bei Kaiserwetter dazu der Kirchenzug am Feuerwehraus zur Aufstellung. Die D\u00f6feringer Blaskapelle f\u00fchrte Zug an, gefolgt von der Geistlichkeit und den Vereinen.<\/p>\n<p>Der Festgottesgottesdienst wurde vom D\u00f6feringer Kirchenchor unter der Leitung von Barbara Zwicknagl, verst\u00e4rkt mit den Instrumentalisten Lena Dirscherl (Orgel) Rudi Zwicknagl (Trompete) und Anna Dirscherl an der Geige, gestaltet. Im Altarraum nahmen Pfarrer Alfons Eder, Pfarrer Erwin Bauer, Pater Alois Stautner und Diakon Alfons Eiber, Platz. Die Festpredigt \u00fcbernahm dann der fr\u00fchere Pfarrer der Pfarrei D\u00f6fering, Erwin Bauer, welche er von 1987 \u20132003 leitete. In dieser Zeit entstand vor allem die Kirche im jetzigen Erscheinungsbild, die neue Orgel sowie die Zusammenlegung der Pfarreien Sch\u00f6nthal und D\u00f6fering.<\/p>\n<p>Zu Beginn nahm er Bezug auf den Propheten Jeremia:<\/p>\n<p>\u201eDer Prophet Jeremia forderte die Bewohner Juda von Jerusalem auf als er schwere Zeiten aufziehen sah: Nehmt Neuland unter den Pflug und s\u00e4ht nicht in die Dornen!<\/p>\n<p>Als Aufruf zur Buse und Umkehr war dieser, in erster Linie an die Priester der damaligen Zeit als der pers\u00f6nliche Vorteil vorne angestellt wurde und Ver\u00e4nderung eingebremst wurde, gedacht. Auf die heutige Zeit \u00fcbertragen legte er der Kirche und den Gl\u00e4ubigen nahe, neue Wege zu beschreiten und damit Neuland zu betreten. Als Pfarrer Bauer 1987 die erste Zusammenlegung von Pfarreien in der Di\u00f6zese Regenburg angehen durfte, war das sicher das Betreten von Neuland. Auch heute muss mit der weiteren Zusammenlegung von vielen Pfarreien wieder Neuland betreten werden um dem Priestermangel zu begegnen. F\u00fcr den einzelnen bedeutet es vom Gewohnten Abschied zu nehmen. Trotz aller Bedenken sollten die Christen darin eine Chance sehen, denn Neues ist nicht unbedingt schlecht. Nur mit Mut und Wagnis k\u00f6nnen wir die kommenden Herausforderungen bestehen. Heruntergebrochen auf eine Pfarrei bedeutet es, \u00a0dass man vor Ort die Dinge zu einem Besseren f\u00fchrt und Neuland unter den Pflug nimmt auch wenn es anstrengend ist. Das geht aber zur Zusammen, denn was helfen die sch\u00f6nsten Kirchen und Pfarrheime, wenn die Menschen fehlen? Zum Abschluss zitierte er noch Papst Franziskus: \u201eEs ist notwendig, dass die Pfarrh\u00f6fe und Gemeinden zu Orten werden, von denen die getauften als Missionare ausziehen und bei der R\u00fcckkehr mit Freude von den Wundern, die er Herrn gewirkt hat, erz\u00e4hlen.\u201c<\/p>\n<p>Auch der Erste B\u00fcrgermeister der Pfarrei Sch\u00f6nthal \u00fcberbrachte die besten W\u00fcnsche der Gemeinde:<\/p>\n<p>\u201eMit Blick auf die Vergangenheit von D\u00f6fering ist das 100- j\u00e4hrige Fest ein sehr junger Geburtstag, denn es gibt Auszeichnungen in denen D\u00f6fering schon 1297 als Pfarrei aufgef\u00fchrt wird. F\u00fcr das Umland und auch f\u00fcr D\u00f6fering kamen in der Folgezeit schwere Zeiten mit den Hussiteneinf\u00e4llen und der Reformation. 1557 wurde der katholische Priester vertrieben und D\u00f6fering musste mehrfach die Konfession wechseln und verarmte in Folge nach dem 30- j\u00e4hrigen Krieg. In den kommenden Jahrhunderten musste die Kirche zweimal aufgebaut werden ehe 1924 die Pfarrei D\u00f6fering neu errichtet werden konnte. Gl\u00e4ubige Menschen haben die Kirche aufgebaut und getragen wie sich heute ist. Jung, aktiv und innovativ pr\u00e4sentiert sie sich. So sind heute Kommune und Pfarrei Heimat f\u00fcr unsere Menschen. Die Gemeinde wird auch in Zukunft an der Seite der Pfarrei D\u00f6fering stehen.<\/p>\n<p>Im Anschluss fand dann das weltliche Fest im Umfeld um die D\u00f6feringer Kirche statt. Am Vortag wurde eigens ein Zelt aufgestellt. In der Garage vom Gasthaus Windmai\u00dfer konnte der OGV dankenswerte Weise die Festk\u00fcche einrichten. Die FFW D\u00f6fering \u00fcbernahm den Ausschank und die KLB konnte wieder zahlreiche Damen zu leckeren Kuchenspende \u00fcberreden. Die OGV Kindergruppe hatte gro\u00dfen Zulauf beim Kinderschminken. Auch haben die Kinder zwei Leinw\u00e4nde als Erinnerung gestaltet. Im Jugendheim wurde eine gro\u00dfe Fotoausstellung, die mit Bildmaterial von 1911-2024 einen gro\u00dfen Bogen aufspannte, angeboten. Dabei wurde Bildmaterial gr\u00f6\u00dftenteils von Peter Sch\u00fctz (Zweitraum ca. 1911 -1980) Sepp Schneider +21.07.2016 (Zeitraum ca. 1985-2008) und Roland Dirscherl (Zeitraum 2006-2024) verwendet. Viele D\u00f6feringer konnten sich selbst, ihre Eltern oder sogar Gro\u00dfeltern auf den Bildern finden. Jeder Verein bekam eine Stellwand. Auch das Kirchenleben, die Ministranten oder auch bisher nicht ver\u00f6ffentlichtes Bildmaterial von den zahlreichen Bauma\u00dfnahmen waren zu sehen. Die Galerie der Jahrg\u00e4nge der Kommunionkinder d\u00fcrfte gef\u00fchlt der Renner gewesen sein.<\/p>\n<p>Die Pfarrei D\u00f6fering\u00a0 ist mit dem Kirchenumbau und dem sp\u00e4teren\u00a0 Neubau des Pfarr-, Dorf-, und Jugendheims heute sicher die Summe von vielen richtigen Entscheidungen die im Einklang zwischen Pfarrer, Kirchenverwaltung und Pfarrgemeinderat getroffen wurden und kann sich wie B\u00fcrgermeister Wallinger zurecht bemerkte als jung, aktiv und innovativ bezeichnen und ist so f\u00fcr die kommenden Zeit bestens ger\u00fcstet.<\/p>\n<p>Impressionen vom Fest:-)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240720_140856.jpg\" alt=\"\" width=\"750\" height=\"423\" class=\"alignnone size-large wp-image-19530\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240720_140856.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240720_140856-300x169.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240720_140856-768x433.jpg 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240720_135213.jpg\" alt=\"\" width=\"750\" height=\"423\" class=\"alignnone size-large wp-image-19529\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240720_135213.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240720_135213-300x169.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240720_135213-768x433.jpg 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240720_173121.jpg\" alt=\"\" width=\"750\" height=\"423\" class=\"alignnone size-large wp-image-19531\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240720_173121.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240720_173121-300x169.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240720_173121-768x433.jpg 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_095248.jpg\" alt=\"\" width=\"530\" height=\"940\" class=\"alignnone  wp-image-19534\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_095248.jpg 577w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_095248-169x300.jpg 169w\" sizes=\"auto, (max-width: 530px) 100vw, 530px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002846.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19547\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002846.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002846-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002846-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002846-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002850.jpg\" alt=\"\" width=\"683\" height=\"1024\" class=\"alignnone size-large wp-image-19548\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002850.jpg 683w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002850-200x300.jpg 200w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002857.jpg\" alt=\"\" width=\"683\" height=\"1024\" class=\"alignnone size-large wp-image-19549\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002857.jpg 683w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002857-200x300.jpg 200w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002868.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19550\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002868.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002868-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002868-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002868-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002873.jpg\" alt=\"\" width=\"683\" height=\"1024\" class=\"alignnone size-large wp-image-19551\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002873.jpg 683w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002873-200x300.jpg 200w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002885.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19552\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002885.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002885-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002885-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002885-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002898.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19554\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002898.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002898-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002898-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002898-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002901.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19555\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002901.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002901-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002901-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002901-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002907.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19556\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002907.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002907-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002907-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002907-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002918.jpg\" alt=\"\" width=\"683\" height=\"1024\" class=\"alignnone size-large wp-image-19557\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002918.jpg 683w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002918-200x300.jpg 200w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240720_173623.jpg\" alt=\"\" width=\"750\" height=\"423\" class=\"alignnone size-large wp-image-19533\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240720_173623.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240720_173623-300x169.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240720_173623-768x433.jpg 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> \u00a0<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_112616.jpg\" alt=\"\" width=\"750\" height=\"423\" class=\"alignnone size-large wp-image-19535\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_112616.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_112616-300x169.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_112616-768x433.jpg 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_112630.jpg\" alt=\"\" width=\"750\" height=\"423\" class=\"alignnone size-large wp-image-19536\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_112630.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_112630-300x169.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_112630-768x433.jpg 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_112657.jpg\" alt=\"\" width=\"750\" height=\"423\" class=\"alignnone size-large wp-image-19537\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_112657.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_112657-300x169.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_112657-768x433.jpg 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_112702.jpg\" alt=\"\" width=\"750\" height=\"423\" class=\"alignnone size-large wp-image-19538\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_112702.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_112702-300x169.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_112702-768x433.jpg 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_115328.jpg\" alt=\"\" width=\"750\" height=\"423\" class=\"alignnone size-large wp-image-19539\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_115328.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_115328-300x169.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_115328-768x433.jpg 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_124908.jpg\" alt=\"\" width=\"750\" height=\"422\" class=\"alignnone size-large wp-image-19540\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_124908.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_124908-300x169.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_124908-768x432.jpg 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> \u00a0<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_130920.jpg\" alt=\"\" width=\"750\" height=\"422\" class=\"alignnone size-large wp-image-19542\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_130920.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_130920-300x169.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_130920-768x432.jpg 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_131539.jpg\" alt=\"\" width=\"750\" height=\"422\" class=\"alignnone size-large wp-image-19543\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_131539.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_131539-300x169.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_131539-768x432.jpg 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_134353.jpg\" alt=\"\" width=\"750\" height=\"422\" class=\"alignnone size-large wp-image-19544\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_134353.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_134353-300x169.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_134353-768x432.jpg 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_135333.jpg\" alt=\"\" width=\"750\" height=\"423\" class=\"alignnone size-large wp-image-19545\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_135333.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_135333-300x169.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_135333-768x433.jpg 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002927.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19558\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002927.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002927-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002927-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002927-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002931.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19559\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002931.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002931-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002931-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002931-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002932.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19560\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002932.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002932-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002932-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002932-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002933.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19561\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002933.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002933-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002933-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002933-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002936.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19562\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002936.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002936-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002936-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002936-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002937.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19563\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002937.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002937-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002937-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002937-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002938.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19564\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002938.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002938-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002938-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002938-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002941.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19565\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002941.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002941-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002941-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002941-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002942.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19566\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002942.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002942-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002942-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002942-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002943.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19567\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002943.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002943-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002943-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002943-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002944.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19568\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002944.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002944-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002944-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002944-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002947.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19569\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002947.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002947-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002947-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002947-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002949.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19570\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002949.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002949-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002949-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002949-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002950.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19571\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002950.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002950-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002950-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002950-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002951.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19572\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002951.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002951-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002951-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002951-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002955.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19573\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002955.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002955-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002955-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002955-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002958.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19574\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002958.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002958-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002958-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002958-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002959.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19575\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002959.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002959-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002959-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002959-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002961.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19576\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002961.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002961-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002961-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002961-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002962.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19577\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002962.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002962-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002962-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002962-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002964.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19578\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002964.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002964-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002964-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002964-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_130239.jpg\" alt=\"\" width=\"577\" height=\"1024\" class=\"alignnone size-large wp-image-19541\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_130239.jpg 577w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_130239-169x300.jpg 169w\" sizes=\"auto, (max-width: 577px) 100vw, 577px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002966.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19579\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002966.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002966-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002966-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002966-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002968.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19580\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002968.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002968-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002968-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002968-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002975.jpg\" alt=\"\" width=\"683\" height=\"1024\" class=\"alignnone size-large wp-image-19581\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002975.jpg 683w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002975-200x300.jpg 200w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002983.jpg\" alt=\"\" width=\"683\" height=\"1024\" class=\"alignnone size-large wp-image-19583\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002983.jpg 683w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002983-200x300.jpg 200w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002980.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19582\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002980.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002980-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002980-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002980-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> \u00a0<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002984.jpg\" alt=\"\" width=\"683\" height=\"1024\" class=\"alignnone size-large wp-image-19584\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002984.jpg 683w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002984-200x300.jpg 200w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002985.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19585\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002985.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002985-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002985-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002985-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002988.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19586\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002988.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002988-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002988-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002988-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002996.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19587\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002996.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002996-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002996-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1002996-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003000.jpg\" alt=\"\" width=\"683\" height=\"1024\" class=\"alignnone size-large wp-image-19588\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003000.jpg 683w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003000-200x300.jpg 200w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003005.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19589\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003005.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003005-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003005-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003005-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003006.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19590\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003006.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003006-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003006-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003006-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003007.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19591\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003007.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003007-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003007-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003007-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003008.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19592\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003008.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003008-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003008-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1003008-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_174615.jpg\" alt=\"\" width=\"750\" height=\"423\" class=\"alignnone size-large wp-image-19546\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_174615.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_174615-300x169.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_174615-768x433.jpg 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240720_104442.jpg\" alt=\"\" width=\"820\" height=\"462\" class=\"alignnone  wp-image-19528\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240720_104442.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240720_104442-300x169.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240720_104442-768x433.jpg 768w\" sizes=\"auto, (max-width: 820px) 100vw, 820px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>100 Jahre Pfarrei D\u00f6fering &nbsp; Mit \u201ejung, aktiv und innovativ\u201c beschrieb B\u00fcrgermeister Ludwig Wallinger die Pfarrei St. \u00c4gidius D\u00f6fering anl\u00e4\u00dflich Ihres 100. Neugr\u00fcndungsfestes und traf damit den Nagel auf den Kopf. Am vergangenen Sonntag feierte die Pfarrei St. \u00c4gidius D\u00f6fering ihren 100-j\u00e4hriges Bestehen als H\u00f6hepunkt eines Jubeljahres als gro\u00dfe Familie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19534,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-19527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-doefering"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>100 Jahre Pfarrei D\u00f6fering - Informationsseite und Seelsorgeeinheit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-sdh.de\/side\/100-jahre-pfarrei-doefering\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"100 Jahre Pfarrei D\u00f6fering - Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"og:description\" content=\"100 Jahre Pfarrei D\u00f6fering &nbsp; Mit \u201ejung, aktiv und innovativ\u201c beschrieb B\u00fcrgermeister Ludwig Wallinger die Pfarrei St. \u00c4gidius D\u00f6fering anl\u00e4\u00dflich Ihres 100. Neugr\u00fcndungsfestes und traf damit den Nagel auf den Kopf. Am vergangenen Sonntag feierte die Pfarrei St. \u00c4gidius D\u00f6fering ihren 100-j\u00e4hriges Bestehen als H\u00f6hepunkt eines Jubeljahres als gro\u00dfe Familie [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-sdh.de\/side\/100-jahre-pfarrei-doefering\/\" \/>\n<meta property=\"og:site_name\" content=\"Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-26T19:10:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_095248.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"577\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dirscherl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dirscherl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/100-jahre-pfarrei-doefering\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/100-jahre-pfarrei-doefering\\\/\"},\"author\":{\"name\":\"Dirscherl\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/03813c96da9249c1923a325c77818b1a\"},\"headline\":\"100 Jahre Pfarrei D\u00f6fering\",\"datePublished\":\"2024-07-26T19:10:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/100-jahre-pfarrei-doefering\\\/\"},\"wordCount\":932,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/100-jahre-pfarrei-doefering\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/20240721_095248.jpg\",\"articleSection\":[\"D\u00f6fering\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/100-jahre-pfarrei-doefering\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/100-jahre-pfarrei-doefering\\\/\",\"name\":\"100 Jahre Pfarrei D\u00f6fering - Informationsseite und Seelsorgeeinheit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/100-jahre-pfarrei-doefering\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/100-jahre-pfarrei-doefering\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/20240721_095248.jpg\",\"datePublished\":\"2024-07-26T19:10:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/100-jahre-pfarrei-doefering\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/100-jahre-pfarrei-doefering\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/100-jahre-pfarrei-doefering\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/20240721_095248.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/20240721_095248.jpg\",\"width\":577,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/100-jahre-pfarrei-doefering\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"100 Jahre Pfarrei D\u00f6fering\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"description\":\"Informationsseite und Seelsorgeeinheit\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"width\":438,\"height\":191,\"caption\":\"Informationsseite und Seelsorgeeinheit\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/03813c96da9249c1923a325c77818b1a\",\"name\":\"Dirscherl\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/author\\\/kirchesdh\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"100 Jahre Pfarrei D\u00f6fering - Informationsseite und Seelsorgeeinheit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-sdh.de\/side\/100-jahre-pfarrei-doefering\/","og_locale":"de_DE","og_type":"article","og_title":"100 Jahre Pfarrei D\u00f6fering - Informationsseite und Seelsorgeeinheit","og_description":"100 Jahre Pfarrei D\u00f6fering &nbsp; Mit \u201ejung, aktiv und innovativ\u201c beschrieb B\u00fcrgermeister Ludwig Wallinger die Pfarrei St. \u00c4gidius D\u00f6fering anl\u00e4\u00dflich Ihres 100. Neugr\u00fcndungsfestes und traf damit den Nagel auf den Kopf. Am vergangenen Sonntag feierte die Pfarrei St. \u00c4gidius D\u00f6fering ihren 100-j\u00e4hriges Bestehen als H\u00f6hepunkt eines Jubeljahres als gro\u00dfe Familie [&hellip;]","og_url":"https:\/\/www.kirche-sdh.de\/side\/100-jahre-pfarrei-doefering\/","og_site_name":"Informationsseite und Seelsorgeeinheit","article_published_time":"2024-07-26T19:10:51+00:00","og_image":[{"width":577,"height":1024,"url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_095248.jpg","type":"image\/jpeg"}],"author":"Dirscherl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Dirscherl","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kirche-sdh.de\/side\/100-jahre-pfarrei-doefering\/#article","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/100-jahre-pfarrei-doefering\/"},"author":{"name":"Dirscherl","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/03813c96da9249c1923a325c77818b1a"},"headline":"100 Jahre Pfarrei D\u00f6fering","datePublished":"2024-07-26T19:10:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/100-jahre-pfarrei-doefering\/"},"wordCount":932,"publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/100-jahre-pfarrei-doefering\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_095248.jpg","articleSection":["D\u00f6fering"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kirche-sdh.de\/side\/100-jahre-pfarrei-doefering\/","url":"https:\/\/www.kirche-sdh.de\/side\/100-jahre-pfarrei-doefering\/","name":"100 Jahre Pfarrei D\u00f6fering - Informationsseite und Seelsorgeeinheit","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/100-jahre-pfarrei-doefering\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/100-jahre-pfarrei-doefering\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_095248.jpg","datePublished":"2024-07-26T19:10:51+00:00","breadcrumb":{"@id":"https:\/\/www.kirche-sdh.de\/side\/100-jahre-pfarrei-doefering\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-sdh.de\/side\/100-jahre-pfarrei-doefering\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/100-jahre-pfarrei-doefering\/#primaryimage","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_095248.jpg","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/20240721_095248.jpg","width":577,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-sdh.de\/side\/100-jahre-pfarrei-doefering\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-sdh.de\/side\/"},{"@type":"ListItem","position":2,"name":"100 Jahre Pfarrei D\u00f6fering"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-sdh.de\/side\/#website","url":"https:\/\/www.kirche-sdh.de\/side\/","name":"Informationsseite und Seelsorgeeinheit","description":"Informationsseite und Seelsorgeeinheit","publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-sdh.de\/side\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.kirche-sdh.de\/side\/#organization","name":"Informationsseite und Seelsorgeeinheit","url":"https:\/\/www.kirche-sdh.de\/side\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","width":438,"height":191,"caption":"Informationsseite und Seelsorgeeinheit"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/03813c96da9249c1923a325c77818b1a","name":"Dirscherl","url":"https:\/\/www.kirche-sdh.de\/side\/author\/kirchesdh\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/19527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/comments?post=19527"}],"version-history":[{"count":0,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/19527\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media\/19534"}],"wp:attachment":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media?parent=19527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/categories?post=19527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/tags?post=19527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}