{"id":19361,"date":"2024-04-01T22:37:52","date_gmt":"2024-04-01T20:37:52","guid":{"rendered":"https:\/\/www.kirche-sdh.de\/side\/?p=19361"},"modified":"2024-04-01T22:37:52","modified_gmt":"2024-04-01T20:37:52","slug":"er-ist-auferstanden-3","status":"publish","type":"post","link":"https:\/\/www.kirche-sdh.de\/side\/er-ist-auferstanden-3\/","title":{"rendered":"\u201eEr ist auferstanden\u201c"},"content":{"rendered":"<p><strong>Oh du fr\u00f6hliche, gnadenbringende Osterzeit &#8211; gemeinsames Osterfr\u00fchst\u00fcck <\/strong><\/p>\n<p><strong>Sch\u00f6nthal<\/strong>. Die Pfarrei Sch\u00f6nthal hat mit der Auferstehungsfeier am fr\u00fchen Ostersonntagmorgen das Osterfest als H\u00f6hepunkt des Kirchenjahres feierlich begangen. Die freudige Nachricht von der Auferstehung Jesu wurde von Pfarrer Alfons Eder verk\u00fcndet. Er beschrieb Ostern als Mitte und H\u00f6hepunkt zwischen Weihnachten und Pfingsten, an dessen Nagel die ganze Christenheit h\u00e4nge. \u00a0<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2735-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1610\" class=\"alignnone size-full wp-image-19364\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2735-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2735-300x189.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2735-1024x644.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2735-768x483.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2735-1536x966.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2735-2048x1288.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2744-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" class=\"alignnone size-full wp-image-19365\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2744-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2744-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2744-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2744-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2744-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2744-2048x1365.jpg 2048w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2744-360x240.jpg 360w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p>Dies ist die selige Nacht, in der Christus die Ketten des Todes zerbrach und aus der Tiefe als Sieger emporstieg\u201c, verk\u00fcndete Pfarrer Eder freudig die frohe Botschaft von der Auferstehung. Die Feierlichkeiten hierzu er\u00f6ffnete der Geistliche mit der Segnung des Osterfeuers und dem Lobpreis der Osterkerze vor der Pfarrkirche und dem \u201eExultet\u201c \u2013 dem gro\u00dfen \u00f6sterlichen Lobgesang. Mit dem dreimaligen Ruf \u201eLumen Christi\u201c und der Antwort \u201eDeo gracias\u201c hielt das Feuer der Osterkerze Einzug in die noch dunkle Pfarrkirche Die vielen Ministranten gaben es an die versammelten Gl\u00e4ubigen weiter und erhellten das Gotteshaus im Kerzenlicht der Osternacht.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2742-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" class=\"alignnone size-full wp-image-19363\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2742-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2742-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2742-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2742-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2742-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2742-2048x1365.jpg 2048w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2742-360x240.jpg 360w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p>Von Gottes Sch\u00f6pfung, der Befreiung und der Flucht der Israeliten aus \u00c4gypten durch das Rote Meer zeugten die Lesungen als zentrale Stellen aus dem Alten Testament. Die Lesung aus dem Neuen Testament verk\u00fcndete die Befreiung vom B\u00f6sen durch die Anteilnahme am Tod und der Auferstehung Jesu aller Getauften. Im Evangelium verlas Pfarrer Eder die freudige Osterbotschaft der Auferstehung Jesu von den Toten. \u201eErschreckt nicht, er ist auferstanden\u201c verlautete die Frohbotschaft des Engels vor dem leeren Grab an die an die Grabstelle gekommenen Frauen.<\/p>\n<p>Seine Osterpredigt begann Pfarrer Eder mit dem heutigen Weihnachtslied \u201eOh du fr\u00f6hliche\u201c. Als 2016 der Kirchenchor im th\u00fcringischen Weimar dieses Lied in der Osternachtsfeier gesungen habe sei ein Raunen durch die Kirche gegangen. In den Strophen des gesungenen Liedes habe es allerdings \u201egnadenbringende Osterzeit, Christ ist erstanden\u201c gehei\u00dfen. Zudem sei vielen nicht bekannt, dass es sich bei dem Lied fr\u00fcher um ein Allfeiertagslied gehandelt habe. Die erste Strophe sei Weihnachten, die zweite Strophe Ostern und die dritte Strophe Pfingsten gewidmet gewesen. Ostern und die Auferstehung Jesu als Nagel, an dem das Christentum h\u00e4nge, sei als H\u00f6hepunkt und Mitte des gesamten Kirchenjahres eingerahmt von Weihnachten und Pfingsten zeitlich und vom Rang treffend in der urspr\u00fcnglichen Liedfassung. Das reine Weihnachtslied sei von Johann Daniel Balk geschrieben worden. Obwohl vier seiner Kinder an Typhus gestorben seien habe der evangelische Kirchenlieddichter an der \u00fcbersch\u00e4umenden und fr\u00f6hlichen Gottesgewissheit festgehalten. Selbst der deutsche Schriftsteller Rainer Kunze, der sich nicht als Christ bezeichnete, sei angetan gewesen von den Glocken, die sich angesichts des leeren Grabes vor Freude \u00fcberschlugen, und dem seit 2000 Jahren w\u00e4hrenden Staunen.<\/p>\n<p>Nach der mit geweihten Osterwasser vorgenommenen Segnung der Gl\u00e4ubigen bekr\u00e4ftige die Pfarrgemeinde den in der Auferstehung geschenkten Glauben im Taufbekenntnis und der gemeinsamen Feier der Eucharistie.<\/p>\n<p>Der Kirchenchor Sch\u00f6nthal unter Leitung von Edith Pongratz und Rudi Gilch an der Orgel bildeten eine festliche Kulisse f\u00fcr den Gottesdienst. Musikalisch brachte der Chor die Botschaft der Auferstehung zum Ausdruck. Mit dem Gloria der lateinischen Messe hielten auch die Glocken und die Orgel wieder Einzug in das Gotteshaus.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2748-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" class=\"alignnone size-full wp-image-19366\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2748-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2748-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2748-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2748-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2748-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2748-2048x1365.jpg 2048w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2748-360x240.jpg 360w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2749-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" class=\"alignnone size-full wp-image-19367\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2749-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2749-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2749-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2749-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2749-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2749-2048x1365.jpg 2048w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2749-360x240.jpg 360w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p>Im Anschluss an die Auferstehungsfeier war die Kirchengemeinde vom Pfarrgemeinderat zum gemeinsamen Osterfr\u00fchst\u00fcck in den Augustinersaal des Pfarr- und Jugendheims geladen. Pfarrer Eder sprach das Segensgebet und er\u00f6ffnete das reichhaltige Buffet das mit einer gro\u00dfen Auswahl an Wurst und K\u00e4se, Kuchen und Obst, oder auch einem Glas Sekt aufwartete.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2752-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" class=\"alignnone size-full wp-image-19368\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2752-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2752-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2752-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2752-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2752-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2752-2048x1365.jpg 2048w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2752-360x240.jpg 360w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2755-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" class=\"alignnone size-full wp-image-19362\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2755-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2755-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2755-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2755-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2755-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2755-2048x1365.jpg 2048w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2755-360x240.jpg 360w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oh du fr\u00f6hliche, gnadenbringende Osterzeit &#8211; gemeinsames Osterfr\u00fchst\u00fcck Sch\u00f6nthal. Die Pfarrei Sch\u00f6nthal hat mit der Auferstehungsfeier am fr\u00fchen Ostersonntagmorgen das Osterfest als H\u00f6hepunkt des Kirchenjahres feierlich begangen. Die freudige Nachricht von der Auferstehung Jesu wurde von Pfarrer Alfons Eder verk\u00fcndet. Er beschrieb Ostern als Mitte und H\u00f6hepunkt zwischen Weihnachten und [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":19363,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-19361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schoenthal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201eEr ist auferstanden\u201c - Informationsseite und Seelsorgeeinheit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-sdh.de\/side\/er-ist-auferstanden-3\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201eEr ist auferstanden\u201c - Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"og:description\" content=\"Oh du fr\u00f6hliche, gnadenbringende Osterzeit &#8211; gemeinsames Osterfr\u00fchst\u00fcck Sch\u00f6nthal. Die Pfarrei Sch\u00f6nthal hat mit der Auferstehungsfeier am fr\u00fchen Ostersonntagmorgen das Osterfest als H\u00f6hepunkt des Kirchenjahres feierlich begangen. Die freudige Nachricht von der Auferstehung Jesu wurde von Pfarrer Alfons Eder verk\u00fcndet. Er beschrieb Ostern als Mitte und H\u00f6hepunkt zwischen Weihnachten und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-sdh.de\/side\/er-ist-auferstanden-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-01T20:37:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2742-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin Zangl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Zangl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/er-ist-auferstanden-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/er-ist-auferstanden-3\\\/\"},\"author\":{\"name\":\"Martin Zangl\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/e05baeb81583d4659c11ea77b24c3640\"},\"headline\":\"\u201eEr ist auferstanden\u201c\",\"datePublished\":\"2024-04-01T20:37:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/er-ist-auferstanden-3\\\/\"},\"wordCount\":576,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/er-ist-auferstanden-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/IMG_2742-scaled.jpg\",\"articleSection\":[\"Sch\u00f6nthal\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/er-ist-auferstanden-3\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/er-ist-auferstanden-3\\\/\",\"name\":\"\u201eEr ist auferstanden\u201c - Informationsseite und Seelsorgeeinheit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/er-ist-auferstanden-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/er-ist-auferstanden-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/IMG_2742-scaled.jpg\",\"datePublished\":\"2024-04-01T20:37:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/er-ist-auferstanden-3\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/er-ist-auferstanden-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/er-ist-auferstanden-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/IMG_2742-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/IMG_2742-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/er-ist-auferstanden-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201eEr ist auferstanden\u201c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"description\":\"Informationsseite und Seelsorgeeinheit\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"width\":438,\"height\":191,\"caption\":\"Informationsseite und Seelsorgeeinheit\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/e05baeb81583d4659c11ea77b24c3640\",\"name\":\"Martin Zangl\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/author\\\/zangl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201eEr ist auferstanden\u201c - Informationsseite und Seelsorgeeinheit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-sdh.de\/side\/er-ist-auferstanden-3\/","og_locale":"de_DE","og_type":"article","og_title":"\u201eEr ist auferstanden\u201c - Informationsseite und Seelsorgeeinheit","og_description":"Oh du fr\u00f6hliche, gnadenbringende Osterzeit &#8211; gemeinsames Osterfr\u00fchst\u00fcck Sch\u00f6nthal. Die Pfarrei Sch\u00f6nthal hat mit der Auferstehungsfeier am fr\u00fchen Ostersonntagmorgen das Osterfest als H\u00f6hepunkt des Kirchenjahres feierlich begangen. Die freudige Nachricht von der Auferstehung Jesu wurde von Pfarrer Alfons Eder verk\u00fcndet. Er beschrieb Ostern als Mitte und H\u00f6hepunkt zwischen Weihnachten und [&hellip;]","og_url":"https:\/\/www.kirche-sdh.de\/side\/er-ist-auferstanden-3\/","og_site_name":"Informationsseite und Seelsorgeeinheit","article_published_time":"2024-04-01T20:37:52+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2742-scaled.jpg","type":"image\/jpeg"}],"author":"Martin Zangl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Martin Zangl","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kirche-sdh.de\/side\/er-ist-auferstanden-3\/#article","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/er-ist-auferstanden-3\/"},"author":{"name":"Martin Zangl","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/e05baeb81583d4659c11ea77b24c3640"},"headline":"\u201eEr ist auferstanden\u201c","datePublished":"2024-04-01T20:37:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/er-ist-auferstanden-3\/"},"wordCount":576,"publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/er-ist-auferstanden-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2742-scaled.jpg","articleSection":["Sch\u00f6nthal"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kirche-sdh.de\/side\/er-ist-auferstanden-3\/","url":"https:\/\/www.kirche-sdh.de\/side\/er-ist-auferstanden-3\/","name":"\u201eEr ist auferstanden\u201c - Informationsseite und Seelsorgeeinheit","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/er-ist-auferstanden-3\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/er-ist-auferstanden-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2742-scaled.jpg","datePublished":"2024-04-01T20:37:52+00:00","breadcrumb":{"@id":"https:\/\/www.kirche-sdh.de\/side\/er-ist-auferstanden-3\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-sdh.de\/side\/er-ist-auferstanden-3\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/er-ist-auferstanden-3\/#primaryimage","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2742-scaled.jpg","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_2742-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-sdh.de\/side\/er-ist-auferstanden-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-sdh.de\/side\/"},{"@type":"ListItem","position":2,"name":"\u201eEr ist auferstanden\u201c"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-sdh.de\/side\/#website","url":"https:\/\/www.kirche-sdh.de\/side\/","name":"Informationsseite und Seelsorgeeinheit","description":"Informationsseite und Seelsorgeeinheit","publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-sdh.de\/side\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.kirche-sdh.de\/side\/#organization","name":"Informationsseite und Seelsorgeeinheit","url":"https:\/\/www.kirche-sdh.de\/side\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","width":438,"height":191,"caption":"Informationsseite und Seelsorgeeinheit"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/e05baeb81583d4659c11ea77b24c3640","name":"Martin Zangl","url":"https:\/\/www.kirche-sdh.de\/side\/author\/zangl\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/19361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/comments?post=19361"}],"version-history":[{"count":0,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/19361\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media\/19363"}],"wp:attachment":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media?parent=19361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/categories?post=19361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/tags?post=19361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}