{"id":19011,"date":"2023-08-29T22:32:43","date_gmt":"2023-08-29T20:32:43","guid":{"rendered":"https:\/\/www.kirche-sdh.de\/side\/?p=19011"},"modified":"2023-09-13T20:40:17","modified_gmt":"2023-09-13T18:40:17","slug":"kirchenfuehrung-in-doefering","status":"publish","type":"post","link":"https:\/\/www.kirche-sdh.de\/side\/kirchenfuehrung-in-doefering\/","title":{"rendered":"Kirchenf\u00fchrung in D\u00f6fering"},"content":{"rendered":"<p><strong>Die Geschichte der Pfarrei D\u00f6fering erz\u00e4hlt<\/strong><\/p>\n<p>Am vergangenen Sonntagnachmittag fanden sich zahlreiche interessierte in der D\u00f6feringer St. \u00c4gidius Kirche zur Kirchenf\u00fchrung ein zu der die Katholische Erwachsenen Bildung eingeladen hatte. Kreisheimatpfleger Josef Ederer und die Vorsitzende der Gesellschaft f\u00fcr Familienforschung, Elfriede Dirschedl waren auch zugegen.<\/p>\n<p>Der zertifizierte Kirchenentdecker Karl Heinz Hofmann hatte sich dazu in die bewegte Geschichte der D\u00f6feringer Kirche eingelesen. Eine gro\u00dfe Hilfe bei der Recherche war zum einen die 1992 zur Einweihung nach der gro\u00dfen Renovierung erschienene Chronik, welche damals Josef Schneider und Gerhard K\u00fchner verfassten, sowie der Kirchenf\u00fchrer aus 1999 von Gerhard K\u00fchner. Nachdem die Kirchenf\u00fchrung mit dem Patrozinium zusammenviel sprach Hofmann zuerst \u00fcber den Kirchenpatron den Hl. \u00c4gidius. Er wurde um 640 in Athen geboren. Als Einsiedler lebte er jahrelang in einer H\u00f6hle bei N\u00eemes an der M\u00fcndung der Rhone zum Mittelmeer.\u00a0 Dabei ern\u00e4hrte er sich unter anderen von der Milch einer Hirschkuh. W\u00e4hrend der Jagd des Westgotenk\u00f6nigs Wamba fl\u00fcchtete diese Hirschkuh zu \u00c4gidius, der sich sch\u00fctzend vor das Tier stellte und so versehentlich von einem Pfeil getroffen wurde. \u00a0Nachdem er Gott darum bat, dass die Wunde nicht verheilen m\u00f6ge trug er diese bis zu seinem Lebensende. Der K\u00f6nig lie\u00df unter Leitung von \u00c4gidius ein Kloster errichten, die Abtei von Saint-Gilles. Der Hl. \u00c4gidius geh\u00f6rt zu den 14 Nothelfern und ist der einzige der nicht als M\u00e4rtyrer starb. Zu erkennen ist er daher auf Abbildungen an den Insignien seiner Amtsw\u00fcrde (Mitra und Stab) und an der Hirschkuh, die ihm als besonderes Attribut beigegeben ist.<\/p>\n<p>D\u00f6fering wurde am 19.01.1055 das erste Mal urkundlich erw\u00e4hnt. \u00a0Lange Jahrhunderte geh\u00f6rte man zum Erzdekanat Cham. Erst 1857 wurde D\u00f6fering dem Dekanat Waldm\u00fcnchen zugeteilt. Heute geh\u00f6rt man wieder zum Dekanat Cham. Ein schwarzer Tag in der Geschichte von D\u00f6fering war sicher der Fronleichsnamstag 1428 als uns\u00e4gliches Leid \u00fcber Volk und Kirche durch die einfallenden Hussiten gebracht wurde. Die wilden Kriegshorden raubten, pl\u00fcnderten und z\u00fcndeten den Ort an, so dass dieser den Flammen zum Opfer fiel. Der Hussenbierl zwischen D\u00f6fering und Haschaberg erinnert noch heute an diese schreckliche Zeit. Aufgrund der Zugeh\u00f6rigkeit zur Kurpfalz musste die Bev\u00f6lkerung den evangelischen Glauben annehmen. Im Jahr 1625 wurde D\u00f6fering wieder katholisch. Von 1641-1733 wurde das zwischenzeitlich verarmte D\u00f6fering von Pemfling seelsorgerlich versorgt. 1903 wurde D\u00f6fering zur Expositur mit erweiterten Rechten. \u00a01924 wurde D\u00f6fering dann zur Pfarrei erhoben und darf im kommenden Jahr sein 100- j\u00e4hriges Bestehen als Pfarrei begehen.<\/p>\n<p>Die Pfarrkirche musste \u00fcber die Jahre hinweg immer wieder neu errichtet werden. Wie genannt brannte die Kirche schon 1428 v\u00f6llig ab. Die neu errichtete Kirche war um 1704 wieder so bauf\u00e4llig, dass ein Neubau anstand. 1817 wurde das Gotteshaus durch einen Sturm schwer besch\u00e4digt. Ein erneuter Brand im Jahr 1854 verschonte Dorf und Kirche nicht. Die Glocken von D\u00f6fering wurden 1917 und 1942 jeweils in den Kriegswirren beschlagnahmt und eingeschmolzen. Schon am 04.01.1950 konnten die neu beschafften Glocken eingeweiht werden, so dass D\u00f6fering innerhalb von nur 95 Jahren dreimal neu Glocken beschaffen musste. Der ab 1854 errichtete Kirchenneubau wurde f\u00fcr D\u00f6fering zu klein so dass ab 1961\/62 eine aus heutiger Sicht f\u00fcr die damalige Zeit zwar moderne aber misslungene Neugestaltung, welche zu technischen Problemen und irreparablen Sch\u00e4den f\u00fchrte.<\/p>\n<p>In den Jahren 1990-1992 wurde die Kirche unter Leitung von Pfarrer Erwin Bauer und der damaligen Kirchenverwaltung\u00a0 \u00a0so umgebaut, wie sie heute noch zum gro\u00dfen Teil zu sehen ist. F\u00fcr die Ausf\u00fchrung konnten der Architekt Sigi Wild und der bekannte Bildhauer Hans Wurmer gewonnen werden. Die Gestaltung des Innenraumes wurde von Bildhauer Hans Wurmer entwickelt und mit der Architektur abgestimmt, wobei Teile der historischen Kirchenausstattung integriert wurden.<\/p>\n<p>Vom K\u00fcnstler Hans Wurmer wurden ausgef\u00fchrt: Volksaltar, Ambo, Tabernakel Stele, Taufstein, Wandtabernakel f\u00fcr die hl. \u00d6le, Osterleuchter, Apostelleuchter, Altarleuchter, Sedilien, Stuhlwangengestaltung, Glasmalereifenster und Steinfigur des Kirchenpatrons.<\/p>\n<p>Ab 1996 wurde farbig gestaltete Glasfenster eingebaut und in einer Nische am Westgiebel eine Steinfigur von St. \u00c4gidius eingelassen. 1998 wurde mit der Anschaffung einer vierten Glocke die Neugestaltung der Pfarrkirche abgeschlossen werden. Im Jahre 2002 wurde dann die heutige Orgel eingeweiht. Unter dem jetzigen Pfarrer, Alfons Eder fand die letzte Bauma\u00dfnahme 2008 mit der Kirchturmsanierung satt sowie 2011 der Neubau des D\u00f6feringer Pfarrheims. Dass die lebendige D\u00f6feringer Kirche von einem Museum wie es vielerorts schon der Fall ist weit entfernt ist, machte schon der damalige Pfarrer Erwin Bauer 1999 in seinem gelungenen Gru\u00dfwort im damaligen Kirchenf\u00fchrer deutlich. \u201eUnsere Kirche ist ein Sinnbild: Die eigentliche Kirche aus lebendigen Steinen sind wir- alle Getauften und Gefirmten. Jeder hat seinen Platz, an dem er gebraucht wird. Nur alle zusammen sind wir Kirche. Unsere Kirche zeigt uns, dass der Himmel offen ist: Wenn wir uns zur Eucharistie versammeln, zerrei\u00dft f\u00fcr einen Moment der Vorhang zwischen Himmel und Erde\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1001378-1024x683.jpg\" alt=\"\" width=\"750\" height=\"500\" class=\"alignnone size-large wp-image-19012\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1001378-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1001378-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1001378-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1001378-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1001378-2048x1365.jpg 2048w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1001378-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Geschichte der Pfarrei D\u00f6fering erz\u00e4hlt Am vergangenen Sonntagnachmittag fanden sich zahlreiche interessierte in der D\u00f6feringer St. \u00c4gidius Kirche zur Kirchenf\u00fchrung ein zu der die Katholische Erwachsenen Bildung eingeladen hatte. Kreisheimatpfleger Josef Ederer und die Vorsitzende der Gesellschaft f\u00fcr Familienforschung, Elfriede Dirschedl waren auch zugegen. Der zertifizierte Kirchenentdecker Karl Heinz [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19012,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,56],"tags":[],"class_list":["post-19011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-doefering","category-schoenthal-doefering"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kirchenf\u00fchrung in D\u00f6fering - Informationsseite und Seelsorgeeinheit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-sdh.de\/side\/kirchenfuehrung-in-doefering\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kirchenf\u00fchrung in D\u00f6fering - Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"og:description\" content=\"Die Geschichte der Pfarrei D\u00f6fering erz\u00e4hlt Am vergangenen Sonntagnachmittag fanden sich zahlreiche interessierte in der D\u00f6feringer St. \u00c4gidius Kirche zur Kirchenf\u00fchrung ein zu der die Katholische Erwachsenen Bildung eingeladen hatte. Kreisheimatpfleger Josef Ederer und die Vorsitzende der Gesellschaft f\u00fcr Familienforschung, Elfriede Dirschedl waren auch zugegen. Der zertifizierte Kirchenentdecker Karl Heinz [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-sdh.de\/side\/kirchenfuehrung-in-doefering\/\" \/>\n<meta property=\"og:site_name\" content=\"Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-29T20:32:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-13T18:40:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1001378-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dirscherl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dirscherl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/kirchenfuehrung-in-doefering\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/kirchenfuehrung-in-doefering\\\/\"},\"author\":{\"name\":\"Dirscherl\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/03813c96da9249c1923a325c77818b1a\"},\"headline\":\"Kirchenf\u00fchrung in D\u00f6fering\",\"datePublished\":\"2023-08-29T20:32:43+00:00\",\"dateModified\":\"2023-09-13T18:40:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/kirchenfuehrung-in-doefering\\\/\"},\"wordCount\":817,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/kirchenfuehrung-in-doefering\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/P1001378-scaled.jpg\",\"articleSection\":[\"D\u00f6fering\",\"Sch\u00f6nthal\\\/D\u00f6fering\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/kirchenfuehrung-in-doefering\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/kirchenfuehrung-in-doefering\\\/\",\"name\":\"Kirchenf\u00fchrung in D\u00f6fering - Informationsseite und Seelsorgeeinheit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/kirchenfuehrung-in-doefering\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/kirchenfuehrung-in-doefering\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/P1001378-scaled.jpg\",\"datePublished\":\"2023-08-29T20:32:43+00:00\",\"dateModified\":\"2023-09-13T18:40:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/kirchenfuehrung-in-doefering\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/kirchenfuehrung-in-doefering\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/kirchenfuehrung-in-doefering\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/P1001378-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/P1001378-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/kirchenfuehrung-in-doefering\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kirchenf\u00fchrung in D\u00f6fering\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"description\":\"Informationsseite und Seelsorgeeinheit\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"width\":438,\"height\":191,\"caption\":\"Informationsseite und Seelsorgeeinheit\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/03813c96da9249c1923a325c77818b1a\",\"name\":\"Dirscherl\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/author\\\/kirchesdh\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kirchenf\u00fchrung in D\u00f6fering - Informationsseite und Seelsorgeeinheit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-sdh.de\/side\/kirchenfuehrung-in-doefering\/","og_locale":"de_DE","og_type":"article","og_title":"Kirchenf\u00fchrung in D\u00f6fering - Informationsseite und Seelsorgeeinheit","og_description":"Die Geschichte der Pfarrei D\u00f6fering erz\u00e4hlt Am vergangenen Sonntagnachmittag fanden sich zahlreiche interessierte in der D\u00f6feringer St. \u00c4gidius Kirche zur Kirchenf\u00fchrung ein zu der die Katholische Erwachsenen Bildung eingeladen hatte. Kreisheimatpfleger Josef Ederer und die Vorsitzende der Gesellschaft f\u00fcr Familienforschung, Elfriede Dirschedl waren auch zugegen. Der zertifizierte Kirchenentdecker Karl Heinz [&hellip;]","og_url":"https:\/\/www.kirche-sdh.de\/side\/kirchenfuehrung-in-doefering\/","og_site_name":"Informationsseite und Seelsorgeeinheit","article_published_time":"2023-08-29T20:32:43+00:00","article_modified_time":"2023-09-13T18:40:17+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1001378-scaled.jpg","type":"image\/jpeg"}],"author":"Dirscherl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Dirscherl","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kirche-sdh.de\/side\/kirchenfuehrung-in-doefering\/#article","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/kirchenfuehrung-in-doefering\/"},"author":{"name":"Dirscherl","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/03813c96da9249c1923a325c77818b1a"},"headline":"Kirchenf\u00fchrung in D\u00f6fering","datePublished":"2023-08-29T20:32:43+00:00","dateModified":"2023-09-13T18:40:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/kirchenfuehrung-in-doefering\/"},"wordCount":817,"publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/kirchenfuehrung-in-doefering\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1001378-scaled.jpg","articleSection":["D\u00f6fering","Sch\u00f6nthal\/D\u00f6fering"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kirche-sdh.de\/side\/kirchenfuehrung-in-doefering\/","url":"https:\/\/www.kirche-sdh.de\/side\/kirchenfuehrung-in-doefering\/","name":"Kirchenf\u00fchrung in D\u00f6fering - Informationsseite und Seelsorgeeinheit","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/kirchenfuehrung-in-doefering\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/kirchenfuehrung-in-doefering\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1001378-scaled.jpg","datePublished":"2023-08-29T20:32:43+00:00","dateModified":"2023-09-13T18:40:17+00:00","breadcrumb":{"@id":"https:\/\/www.kirche-sdh.de\/side\/kirchenfuehrung-in-doefering\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-sdh.de\/side\/kirchenfuehrung-in-doefering\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/kirchenfuehrung-in-doefering\/#primaryimage","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1001378-scaled.jpg","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/P1001378-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-sdh.de\/side\/kirchenfuehrung-in-doefering\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-sdh.de\/side\/"},{"@type":"ListItem","position":2,"name":"Kirchenf\u00fchrung in D\u00f6fering"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-sdh.de\/side\/#website","url":"https:\/\/www.kirche-sdh.de\/side\/","name":"Informationsseite und Seelsorgeeinheit","description":"Informationsseite und Seelsorgeeinheit","publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-sdh.de\/side\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.kirche-sdh.de\/side\/#organization","name":"Informationsseite und Seelsorgeeinheit","url":"https:\/\/www.kirche-sdh.de\/side\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","width":438,"height":191,"caption":"Informationsseite und Seelsorgeeinheit"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/03813c96da9249c1923a325c77818b1a","name":"Dirscherl","url":"https:\/\/www.kirche-sdh.de\/side\/author\/kirchesdh\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/19011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/comments?post=19011"}],"version-history":[{"count":0,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/19011\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media\/19012"}],"wp:attachment":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media?parent=19011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/categories?post=19011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/tags?post=19011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}