{"id":18778,"date":"2023-01-27T17:54:48","date_gmt":"2023-01-27T16:54:48","guid":{"rendered":"https:\/\/www.kirche-sdh.de\/side\/?p=18778"},"modified":"2023-01-27T17:56:50","modified_gmt":"2023-01-27T16:56:50","slug":"grosser-glaubensbote-und-maertyrer","status":"publish","type":"post","link":"https:\/\/www.kirche-sdh.de\/side\/grosser-glaubensbote-und-maertyrer\/","title":{"rendered":"Gro\u00dfer Glaubensbote und M\u00e4rtyrer"},"content":{"rendered":"<h2><strong>Pfarrgemeinde Sch\u00f6nthal begeht Gedenktag des Heiligen Sebastian &#8211; Sebastianibruderschaft seit 300 Jahren<\/strong><\/h2>\n<p>Zur\u00fcckf\u00fchrend auf die Pestzeit wird der Heilige Sebastian als M\u00e4rtyrer, Nothelfer und Pestheiliger verehrt. Als \u201eMann mit festem R\u00fcckgrat\u201c, der sich gerade im Glauben nicht verbiegen lie\u00df, bezeichnete Pfarrers Alfons Eder den ehemaligen Offizier Sebastian im Festgottesdienst anl\u00e4sslich seines Gedenk- und Namenstags. Dieser wird am 20. Januar begangen und kommt im Zusammenschluss zu einer Sebastianibruderschaft zum besonderen Ausdruck.<\/p>\n<p>Eingef\u00fchrt wurde die Sebastianibruderschaft im Jahr 1723 unter Papst Innozenz XIII und besteht damit in diesem Jahr seit 300 Jahren. Von Pfeilen durchbohrt wird der Heilige Sebastian in der Pfarrkirche Sch\u00f6nthal am rechten Seitenalter dargestellt. Festlich geschm\u00fcckt zeigte sich dieser zum am Sonntag gefeierten Hochfest mit Prozession und Gedenken an die verstorbenen Mitglieder. Die Prozession konnte in diesem Jahr nach zwei Jahren Corona-Zwangspause wieder als gelebtes Glaubenszeugnis stattfinden. Diesen von Sebastian gelebten Glauben brauche es auch und gerade heute, so Pfarrer Eder in seinen begr\u00fc\u00dfenden Worten zu Ehren des gro\u00dfen Glaubensboten und M\u00e4rtyrers.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_0932a-1-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1746\" class=\"alignnone size-full wp-image-18776\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_0932a-1-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_0932a-1-300x205.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_0932a-1-1024x698.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_0932a-1-768x524.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_0932a-1-1536x1048.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_0932a-1-2048x1397.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p>Diakon Alfons Eiber, der gemeinsam mit Pfarrer Eder den Gottesdienst zelebrierte, erinnerte in seiner Predigt an das Leben des heiligen Sebastian und seinen unbeirrbaren Glauben. W\u00e4hrend der gro\u00dfen Christenverfolgung 288 unter Kaiser Diokletian habe Sebastian sein Leben mit und durch Jesus gef\u00fchrt und seinen Glauben dennoch gelebt. Gegen alle ausgesprochenen Drohungen und rohe Gewalt des Kaisers \u201eleistete er verbalen Widerstand und mit \u00dcberzeugung ging er in den Tod.\u201c Bis zu seinem schmerzhaften Ende habe er seinen Alltag so christlich es nur ging gelebt. Auch wenn heute in Europa keine direkte Christenverfolgung herrsche, komme es weltweit zur Unterdr\u00fcckung und Bedrohung von Christen. Hoffnungsvoll gelte noch immer Sebastians Ausspruch \u201eIch f\u00fcrchte kein Unheil, denn du mein Jesus, bist bei mir.\u201c Dies sei vor allem dann der Fall, wenn das Zeugnis aus Liebe gegeben werde. Der Tod sei zwar schlimm, aber die Liebe k\u00f6nne er nicht zerst\u00f6ren. An die Gottesdienstbesucher appellierte Diakon Eiber, Zeugen Christi zu sein und sich den Heiligen Sebastian zum Vorbild zu nehmen.<\/p>\n<p>Der Festgottesdienst, der vom Kirchenchor Sch\u00f6nthal unter Leitung von Edith Pongratz mit Sebastiansliedern und der \u201eBauern-Messe\u201c feierlich gestaltet wurde, fand seinen Abschluss in einer kurzen Prozession mit dem Allerheiligsten durch den Ort. Voran f\u00fchrte das Bildnis des Heiligen Sebastian.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_0942a-1-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1758\" class=\"alignnone size-full wp-image-18777\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_0942a-1-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_0942a-1-300x206.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_0942a-1-1024x703.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_0942a-1-768x527.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_0942a-1-1536x1055.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_0942a-1-2048x1406.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p>Zur\u00fcck in der Pfarrkirche beschloss das \u201eGro\u00dfer Gott wir loben dich\u201c das ehrw\u00fcrdige Hochfest, das schon wegen der Jahrhunderte w\u00e4hrenden Tradition mehr Gottesdienstbesucher und Teilnehmer an der Prozession verdient h\u00e4tte. Zeitgeist und die Folgen der Corona-Pandemie hinterlassen inzwischen auch hier ihre Spuren und liesen zahlreiche Kirchenpl\u00e4tze unbesetzt. Pfarrer Eder dankte dennoch allen f\u00fcr die Mitwirkung und Gestaltung sowie Diakon Alfons Eiber f\u00fcr die Konzelebration. Nach dem Gottesdienst bestand die M\u00f6glichkeit sich in die Sebastianibruderschaft neu aufnehmen zu lassen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pfarrgemeinde Sch\u00f6nthal begeht Gedenktag des Heiligen Sebastian &#8211; Sebastianibruderschaft seit 300 Jahren Zur\u00fcckf\u00fchrend auf die Pestzeit wird der Heilige Sebastian als M\u00e4rtyrer, Nothelfer und Pestheiliger verehrt. Als \u201eMann mit festem R\u00fcckgrat\u201c, der sich gerade im Glauben nicht verbiegen lie\u00df, bezeichnete Pfarrers Alfons Eder den ehemaligen Offizier Sebastian im Festgottesdienst anl\u00e4sslich [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":18777,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-18778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schoenthal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gro\u00dfer Glaubensbote und M\u00e4rtyrer - Informationsseite und Seelsorgeeinheit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-sdh.de\/side\/grosser-glaubensbote-und-maertyrer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gro\u00dfer Glaubensbote und M\u00e4rtyrer - Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"og:description\" content=\"Pfarrgemeinde Sch\u00f6nthal begeht Gedenktag des Heiligen Sebastian &#8211; Sebastianibruderschaft seit 300 Jahren Zur\u00fcckf\u00fchrend auf die Pestzeit wird der Heilige Sebastian als M\u00e4rtyrer, Nothelfer und Pestheiliger verehrt. Als \u201eMann mit festem R\u00fcckgrat\u201c, der sich gerade im Glauben nicht verbiegen lie\u00df, bezeichnete Pfarrers Alfons Eder den ehemaligen Offizier Sebastian im Festgottesdienst anl\u00e4sslich [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-sdh.de\/side\/grosser-glaubensbote-und-maertyrer\/\" \/>\n<meta property=\"og:site_name\" content=\"Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-27T16:54:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-27T16:56:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_0942a-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1758\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin Zangl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Zangl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/grosser-glaubensbote-und-maertyrer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/grosser-glaubensbote-und-maertyrer\\\/\"},\"author\":{\"name\":\"Martin Zangl\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/e05baeb81583d4659c11ea77b24c3640\"},\"headline\":\"Gro\u00dfer Glaubensbote und M\u00e4rtyrer\",\"datePublished\":\"2023-01-27T16:54:48+00:00\",\"dateModified\":\"2023-01-27T16:56:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/grosser-glaubensbote-und-maertyrer\\\/\"},\"wordCount\":474,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/grosser-glaubensbote-und-maertyrer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/IMG_0942a-1-scaled.jpg\",\"articleSection\":[\"Sch\u00f6nthal\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/grosser-glaubensbote-und-maertyrer\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/grosser-glaubensbote-und-maertyrer\\\/\",\"name\":\"Gro\u00dfer Glaubensbote und M\u00e4rtyrer - Informationsseite und Seelsorgeeinheit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/grosser-glaubensbote-und-maertyrer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/grosser-glaubensbote-und-maertyrer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/IMG_0942a-1-scaled.jpg\",\"datePublished\":\"2023-01-27T16:54:48+00:00\",\"dateModified\":\"2023-01-27T16:56:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/grosser-glaubensbote-und-maertyrer\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/grosser-glaubensbote-und-maertyrer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/grosser-glaubensbote-und-maertyrer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/IMG_0942a-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/IMG_0942a-1-scaled.jpg\",\"width\":2560,\"height\":1758},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/grosser-glaubensbote-und-maertyrer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gro\u00dfer Glaubensbote und M\u00e4rtyrer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"description\":\"Informationsseite und Seelsorgeeinheit\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"width\":438,\"height\":191,\"caption\":\"Informationsseite und Seelsorgeeinheit\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/e05baeb81583d4659c11ea77b24c3640\",\"name\":\"Martin Zangl\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/author\\\/zangl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gro\u00dfer Glaubensbote und M\u00e4rtyrer - Informationsseite und Seelsorgeeinheit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-sdh.de\/side\/grosser-glaubensbote-und-maertyrer\/","og_locale":"de_DE","og_type":"article","og_title":"Gro\u00dfer Glaubensbote und M\u00e4rtyrer - Informationsseite und Seelsorgeeinheit","og_description":"Pfarrgemeinde Sch\u00f6nthal begeht Gedenktag des Heiligen Sebastian &#8211; Sebastianibruderschaft seit 300 Jahren Zur\u00fcckf\u00fchrend auf die Pestzeit wird der Heilige Sebastian als M\u00e4rtyrer, Nothelfer und Pestheiliger verehrt. Als \u201eMann mit festem R\u00fcckgrat\u201c, der sich gerade im Glauben nicht verbiegen lie\u00df, bezeichnete Pfarrers Alfons Eder den ehemaligen Offizier Sebastian im Festgottesdienst anl\u00e4sslich [&hellip;]","og_url":"https:\/\/www.kirche-sdh.de\/side\/grosser-glaubensbote-und-maertyrer\/","og_site_name":"Informationsseite und Seelsorgeeinheit","article_published_time":"2023-01-27T16:54:48+00:00","article_modified_time":"2023-01-27T16:56:50+00:00","og_image":[{"width":2560,"height":1758,"url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_0942a-1-scaled.jpg","type":"image\/jpeg"}],"author":"Martin Zangl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Martin Zangl","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kirche-sdh.de\/side\/grosser-glaubensbote-und-maertyrer\/#article","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/grosser-glaubensbote-und-maertyrer\/"},"author":{"name":"Martin Zangl","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/e05baeb81583d4659c11ea77b24c3640"},"headline":"Gro\u00dfer Glaubensbote und M\u00e4rtyrer","datePublished":"2023-01-27T16:54:48+00:00","dateModified":"2023-01-27T16:56:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/grosser-glaubensbote-und-maertyrer\/"},"wordCount":474,"publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/grosser-glaubensbote-und-maertyrer\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_0942a-1-scaled.jpg","articleSection":["Sch\u00f6nthal"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kirche-sdh.de\/side\/grosser-glaubensbote-und-maertyrer\/","url":"https:\/\/www.kirche-sdh.de\/side\/grosser-glaubensbote-und-maertyrer\/","name":"Gro\u00dfer Glaubensbote und M\u00e4rtyrer - Informationsseite und Seelsorgeeinheit","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/grosser-glaubensbote-und-maertyrer\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/grosser-glaubensbote-und-maertyrer\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_0942a-1-scaled.jpg","datePublished":"2023-01-27T16:54:48+00:00","dateModified":"2023-01-27T16:56:50+00:00","breadcrumb":{"@id":"https:\/\/www.kirche-sdh.de\/side\/grosser-glaubensbote-und-maertyrer\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-sdh.de\/side\/grosser-glaubensbote-und-maertyrer\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/grosser-glaubensbote-und-maertyrer\/#primaryimage","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_0942a-1-scaled.jpg","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_0942a-1-scaled.jpg","width":2560,"height":1758},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-sdh.de\/side\/grosser-glaubensbote-und-maertyrer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-sdh.de\/side\/"},{"@type":"ListItem","position":2,"name":"Gro\u00dfer Glaubensbote und M\u00e4rtyrer"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-sdh.de\/side\/#website","url":"https:\/\/www.kirche-sdh.de\/side\/","name":"Informationsseite und Seelsorgeeinheit","description":"Informationsseite und Seelsorgeeinheit","publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-sdh.de\/side\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.kirche-sdh.de\/side\/#organization","name":"Informationsseite und Seelsorgeeinheit","url":"https:\/\/www.kirche-sdh.de\/side\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","width":438,"height":191,"caption":"Informationsseite und Seelsorgeeinheit"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/e05baeb81583d4659c11ea77b24c3640","name":"Martin Zangl","url":"https:\/\/www.kirche-sdh.de\/side\/author\/zangl\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/18778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/comments?post=18778"}],"version-history":[{"count":0,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/18778\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media\/18777"}],"wp:attachment":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media?parent=18778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/categories?post=18778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/tags?post=18778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}