{"id":18443,"date":"2022-06-03T08:45:53","date_gmt":"2022-06-03T06:45:53","guid":{"rendered":"https:\/\/www.kirche-sdh.de\/side\/?p=18443"},"modified":"2022-06-03T08:45:53","modified_gmt":"2022-06-03T06:45:53","slug":"wechsel-im-pfarrgemeinderat","status":"publish","type":"post","link":"https:\/\/www.kirche-sdh.de\/side\/wechsel-im-pfarrgemeinderat\/","title":{"rendered":"Wechsel im Pfarrgemeinderat"},"content":{"rendered":"<p><strong>Pfarrer Alfons Eder dankt den Mitgliedern des bisherigen und des neuen Pfarrgemeinderates<\/strong><\/p>\n<p><strong>Sch\u00f6nthal<\/strong>: F\u00fcr ihre T\u00e4tigkeit im Pfarrgemeinderat wurden im Vorabendgottesdienst zum Muttertag die ausscheidenden Mitglieder des Pfarrgemeinderates Sch\u00f6nthal geehrt. Pfarrer Alfons Eder dankte ihnen f\u00fcr ihre langj\u00e4hrige ehrenamtliche T\u00e4tigkeit zum Wohl der Pfarrei, den neuen Mitgliedern f\u00fcr ihre Bereitschaft zur Kandidatur und Mitarbeit in den kommenden vier Jahren.<\/p>\n<p>Am 20. M\u00e4rz haben die Wahlen zur Bildung des neuen Pfarrgemeinderates stattgefunden. In diesem Gremium, so f\u00fchrte Pfarrer Eder aus, habe er einen Ansprechpartner mit dem die Verantwortung ein St\u00fcck weit geteilt, Beratung und Mitgestaltung erfolgen k\u00f6nne. Die letzte Amtsperiode sei \u00fcberschattet und beeintr\u00e4chtigt gewesen von Corona. Vieles an angedachten Aktivit\u00e4ten musste entfallen. Stattdessen war f\u00fcr die Gottesdienste ein Ordnerdienst zu organisieren und zu \u00fcbernehmen. Sch\u00f6n seien allerdings die Gottesdienste unter freiem Himmel gewesen, gewann Pfarrer Eder der Zeit doch noch etwas Gutes ab.<\/p>\n<p>Es sei ganz normal, dass nach einer gewissen Zeit Mitglieder wieder aufh\u00f6ren m\u00f6chten. Nicht mehr zur Wahl stellten sich Monika B\u00fccherl, Irmgard Ring und Nicole Kainz. Monika B\u00fccherl war 12 Jahre lang im Pfarrgemeinderat, Irmgard Ring acht Jahre und Nicole Kainz vier Jahre. F\u00fcr die aufopferungsvolle und engagierte Mitarbeit zum Wohl der Pfarrei sagte ihnen Pfarrer Eder ein herzliches Vergelt`s Gott. Zum Dank erhielten sie neben einer Dankurkunde des Bistums Regenburg von Pfarrgemeinderatssprecher Maximilian Ruhland eine Sonderm\u00fcnze \u201eGeburt Jesu Christi\u201c und Blumen \u00fcberreicht. Blumen erhielten auch die Mitglieder des neuen Pfarrgemeinderates. Pfarrer Eder durfte dazu Christa Linsmeier, Roland Mauerer, Julia Milling und Susanne Wutz namentlich als neue Mitglieder begr\u00fc\u00dfen und nach vorne bitten. Zusammen mit den bisherigen Pfarrgemeinder\u00e4ten Maximilian Ruhland, Marina Schie\u00dfl und Martin Zangl ergebe sich eine gute Mischung zwischen erfahrenen und neuen Mitgliedern, meinte Pfarrer Eder hoffnungsvoll und w\u00fcnschte sich eine weiterhin gute Zusammenarbeit f\u00fcr die Zukunft. Susanne Wutz und Christa Linsmeier werden sich k\u00fcnftig um die Familiengottesdienste k\u00fcmmern, Julia Milling um die Jugend und die Ministranten, gemeinsam mit Gemeindereferentin Rosa-Maria Roth, und Roland Mauerer werde sich bei Aktivit\u00e4ten und Veranstaltungen einbringen. Mit einem kr\u00e4ftigen Applaus wurden sowohl die ausscheidenden Mitglieder wie auch die Mitglieder des neuen Pfarrgemeinderates von den Gottesdienstbesuchern bedacht.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_8928-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" class=\"alignnone size-full wp-image-18444\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_8928-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_8928-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_8928-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_8928-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_8928-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_8928-2048x1365.jpg 2048w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_8928-360x240.jpg 360w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p>Pfarrer Eder verabschiedete die bisherigen Pfarrgemeinderatsmitglieder Monika B\u00fccherl, Irmgard Ring und Nicole Kainz (erste Reihe von links) und stellte den neuen Pfarrgemeinderat mit Maximilian Ruhland, Marina Schie\u00dfl, Christa Linsmeier, Roland Mauerer, Julia Milling, Susanne Wutz (zweite Reihe von links) sowie Martin Zangl (nicht auf dem Foto) vor. Mit auf dem Foto Gemeindereferentin Rosa-Maria Roth.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pfarrer Alfons Eder dankt den Mitgliedern des bisherigen und des neuen Pfarrgemeinderates Sch\u00f6nthal: F\u00fcr ihre T\u00e4tigkeit im Pfarrgemeinderat wurden im Vorabendgottesdienst zum Muttertag die ausscheidenden Mitglieder des Pfarrgemeinderates Sch\u00f6nthal geehrt. Pfarrer Alfons Eder dankte ihnen f\u00fcr ihre langj\u00e4hrige ehrenamtliche T\u00e4tigkeit zum Wohl der Pfarrei, den neuen Mitgliedern f\u00fcr ihre Bereitschaft [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":18444,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-18443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schoenthal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wechsel im Pfarrgemeinderat - Informationsseite und Seelsorgeeinheit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-sdh.de\/side\/wechsel-im-pfarrgemeinderat\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wechsel im Pfarrgemeinderat - Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"og:description\" content=\"Pfarrer Alfons Eder dankt den Mitgliedern des bisherigen und des neuen Pfarrgemeinderates Sch\u00f6nthal: F\u00fcr ihre T\u00e4tigkeit im Pfarrgemeinderat wurden im Vorabendgottesdienst zum Muttertag die ausscheidenden Mitglieder des Pfarrgemeinderates Sch\u00f6nthal geehrt. Pfarrer Alfons Eder dankte ihnen f\u00fcr ihre langj\u00e4hrige ehrenamtliche T\u00e4tigkeit zum Wohl der Pfarrei, den neuen Mitgliedern f\u00fcr ihre Bereitschaft [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-sdh.de\/side\/wechsel-im-pfarrgemeinderat\/\" \/>\n<meta property=\"og:site_name\" content=\"Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-03T06:45:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_8928-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin Zangl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Zangl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wechsel-im-pfarrgemeinderat\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wechsel-im-pfarrgemeinderat\\\/\"},\"author\":{\"name\":\"Martin Zangl\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/e05baeb81583d4659c11ea77b24c3640\"},\"headline\":\"Wechsel im Pfarrgemeinderat\",\"datePublished\":\"2022-06-03T06:45:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wechsel-im-pfarrgemeinderat\\\/\"},\"wordCount\":436,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wechsel-im-pfarrgemeinderat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/IMG_8928-scaled.jpg\",\"articleSection\":[\"Sch\u00f6nthal\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wechsel-im-pfarrgemeinderat\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wechsel-im-pfarrgemeinderat\\\/\",\"name\":\"Wechsel im Pfarrgemeinderat - Informationsseite und Seelsorgeeinheit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wechsel-im-pfarrgemeinderat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wechsel-im-pfarrgemeinderat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/IMG_8928-scaled.jpg\",\"datePublished\":\"2022-06-03T06:45:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wechsel-im-pfarrgemeinderat\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wechsel-im-pfarrgemeinderat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wechsel-im-pfarrgemeinderat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/IMG_8928-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/IMG_8928-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wechsel-im-pfarrgemeinderat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wechsel im Pfarrgemeinderat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"description\":\"Informationsseite und Seelsorgeeinheit\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"width\":438,\"height\":191,\"caption\":\"Informationsseite und Seelsorgeeinheit\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/e05baeb81583d4659c11ea77b24c3640\",\"name\":\"Martin Zangl\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/author\\\/zangl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wechsel im Pfarrgemeinderat - Informationsseite und Seelsorgeeinheit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-sdh.de\/side\/wechsel-im-pfarrgemeinderat\/","og_locale":"de_DE","og_type":"article","og_title":"Wechsel im Pfarrgemeinderat - Informationsseite und Seelsorgeeinheit","og_description":"Pfarrer Alfons Eder dankt den Mitgliedern des bisherigen und des neuen Pfarrgemeinderates Sch\u00f6nthal: F\u00fcr ihre T\u00e4tigkeit im Pfarrgemeinderat wurden im Vorabendgottesdienst zum Muttertag die ausscheidenden Mitglieder des Pfarrgemeinderates Sch\u00f6nthal geehrt. Pfarrer Alfons Eder dankte ihnen f\u00fcr ihre langj\u00e4hrige ehrenamtliche T\u00e4tigkeit zum Wohl der Pfarrei, den neuen Mitgliedern f\u00fcr ihre Bereitschaft [&hellip;]","og_url":"https:\/\/www.kirche-sdh.de\/side\/wechsel-im-pfarrgemeinderat\/","og_site_name":"Informationsseite und Seelsorgeeinheit","article_published_time":"2022-06-03T06:45:53+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_8928-scaled.jpg","type":"image\/jpeg"}],"author":"Martin Zangl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Martin Zangl","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kirche-sdh.de\/side\/wechsel-im-pfarrgemeinderat\/#article","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/wechsel-im-pfarrgemeinderat\/"},"author":{"name":"Martin Zangl","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/e05baeb81583d4659c11ea77b24c3640"},"headline":"Wechsel im Pfarrgemeinderat","datePublished":"2022-06-03T06:45:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/wechsel-im-pfarrgemeinderat\/"},"wordCount":436,"publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/wechsel-im-pfarrgemeinderat\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_8928-scaled.jpg","articleSection":["Sch\u00f6nthal"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kirche-sdh.de\/side\/wechsel-im-pfarrgemeinderat\/","url":"https:\/\/www.kirche-sdh.de\/side\/wechsel-im-pfarrgemeinderat\/","name":"Wechsel im Pfarrgemeinderat - Informationsseite und Seelsorgeeinheit","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/wechsel-im-pfarrgemeinderat\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/wechsel-im-pfarrgemeinderat\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_8928-scaled.jpg","datePublished":"2022-06-03T06:45:53+00:00","breadcrumb":{"@id":"https:\/\/www.kirche-sdh.de\/side\/wechsel-im-pfarrgemeinderat\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-sdh.de\/side\/wechsel-im-pfarrgemeinderat\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/wechsel-im-pfarrgemeinderat\/#primaryimage","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_8928-scaled.jpg","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/IMG_8928-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-sdh.de\/side\/wechsel-im-pfarrgemeinderat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-sdh.de\/side\/"},{"@type":"ListItem","position":2,"name":"Wechsel im Pfarrgemeinderat"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-sdh.de\/side\/#website","url":"https:\/\/www.kirche-sdh.de\/side\/","name":"Informationsseite und Seelsorgeeinheit","description":"Informationsseite und Seelsorgeeinheit","publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-sdh.de\/side\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.kirche-sdh.de\/side\/#organization","name":"Informationsseite und Seelsorgeeinheit","url":"https:\/\/www.kirche-sdh.de\/side\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","width":438,"height":191,"caption":"Informationsseite und Seelsorgeeinheit"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/e05baeb81583d4659c11ea77b24c3640","name":"Martin Zangl","url":"https:\/\/www.kirche-sdh.de\/side\/author\/zangl\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/18443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/comments?post=18443"}],"version-history":[{"count":0,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/18443\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media\/18444"}],"wp:attachment":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media?parent=18443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/categories?post=18443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/tags?post=18443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}