{"id":12845,"date":"2020-05-10T13:49:34","date_gmt":"2020-05-10T11:49:34","guid":{"rendered":"https:\/\/www.kirche-sdh.de\/side\/?p=12845"},"modified":"2020-06-13T10:09:34","modified_gmt":"2020-06-13T08:09:34","slug":"gottesdienst-mit-abstand","status":"publish","type":"post","link":"https:\/\/www.kirche-sdh.de\/side\/gottesdienst-mit-abstand\/","title":{"rendered":"Gottesdienst mit Abstand"},"content":{"rendered":"<p><strong>Pfarrer Alfons Eder feiert erstmals wieder Gottesdienst mit Gl\u00e4ubigen<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; Unter Einhaltung der strengen Corona-Auflagen d\u00fcrfen seit 4. Mai wieder Gottesdienste mit Beteiligung der Gl\u00e4ubigen gefeiert werden. Rund sieben Wochen waren \u00f6ffentliche Gottesdienste untersagt gewesen. Umso mehr freute sich Pfarrer Alfons Eder am Muttertagssonntag \u00fcber die rund 50 Gottesdienstbesucher die sich trotz Mund-Nasen-Schutz und Desinfektionsmittel zur gemeinsamen Gottesdienstfeier entschlossen hatten. \u201eEine sehr merkw\u00fcrdige Situation\u201c sei es gewesen, vor leeren B\u00e4nken die Eucharistie zu feiern. Auch wenn die M\u00f6glichkeit zur Eucharistiefeier neuerdings gegeben sei, liege dennoch ein langer Weg bis zur Normalit\u00e4t vor allen. Bis dahin gelte es die Auflagen zu beachten und die Hinweise zu befolgen. F\u00fcr die Gottesdienste habe man Sitzpl\u00e4tze zugeteilt, B\u00e4nke abgesperrt, Gotteslob entfernt und Desinfektionsmittel bereitgestellt. Bei den Sonntagsgottesdiensten \u00fcbernehmen Mitglieder des Pfarrgemeinderates und der Kirchenverwaltung einen Ordnerdienst zur Platzeinweisung. Nat\u00fcrlich wolle man vermeiden, dass Gottesdienstbesucher wieder heim geschickt werden m\u00fcssen. Daf\u00fcr sind im Eingangsbereich noch einige Notpl\u00e4tze vorhanden und bei entsprechendem Wetter und ge\u00f6ffneten T\u00fcren k\u00f6nnte auch von drau\u00dfen am Gottesdienst teilgenommen werden.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" class=\"aligncenter size-full wp-image-12846\" alt=\"\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4962-scaled.jpg\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4962-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4962-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4962-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4962-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4962-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4962-2048x1365.jpg 2048w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4962-360x240.jpg 360w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p>Besonders der Kommunionempfang sei ein sensibles Thema. Alle, die die Kommunion empfangen m\u00f6chten, sollten sich eingangs per Handzeichen melden, zum Empfang am Platz verbleiben sowie die Arme weit ausstrecken.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" class=\"aligncenter size-full wp-image-12847\" alt=\"\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4968-scaled.jpg\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4968-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4968-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4968-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4968-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4968-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4968-2048x1365.jpg 2048w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4968-360x240.jpg 360w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p>Weil der Gottesdienst insgesamt aufw\u00e4ndiger ist, findet der sp\u00e4tere Sonntagsgottesdienst bis auf weiteres erst um 10 Uhr statt. Vieles m\u00fcsse ausprobiert und unter Umst\u00e4nden nachgebessert werden, doch wolle man das Beste daraus machen. Angelehnt an das Evangelium appellierte Pfarrer Eder an die Pfarrei \u201edas Herz nicht zu verwirren lassen\u201c und am Glauben festzuhalten. Insgesamt d\u00fcrfe man noch dankbar sein, von Schockbildern wie in Italien verschont geblieben zu sein. Er bat um Verst\u00e4ndnis f\u00fcr die Ma\u00dfnahmen und dankte der Mesnerin Monika Fries und den Mitgliedern vom Pfarrgemeinderat und der Kirchenverwaltung f\u00fcr die Umsetzung und Mithilfe.<\/p>\n<p>&nbsp;<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-12845-1\" width=\"640\" height=\"352\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/VID-20200510-WA0001.mp4?_=1\" \/><a href=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/VID-20200510-WA0001.mp4\">https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/VID-20200510-WA0001.mp4<\/a><\/video><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pfarrer Alfons Eder feiert erstmals wieder Gottesdienst mit Gl\u00e4ubigen &nbsp; &#8211; Unter Einhaltung der strengen Corona-Auflagen d\u00fcrfen seit 4. Mai wieder Gottesdienste mit Beteiligung der Gl\u00e4ubigen gefeiert werden. Rund sieben Wochen waren \u00f6ffentliche Gottesdienste untersagt gewesen. Umso mehr freute sich Pfarrer Alfons Eder am Muttertagssonntag \u00fcber die rund 50 Gottesdienstbesucher [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":12846,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-12845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schoenthal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gottesdienst mit Abstand - Informationsseite und Seelsorgeeinheit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-sdh.de\/side\/gottesdienst-mit-abstand\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gottesdienst mit Abstand - Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"og:description\" content=\"Pfarrer Alfons Eder feiert erstmals wieder Gottesdienst mit Gl\u00e4ubigen &nbsp; &#8211; Unter Einhaltung der strengen Corona-Auflagen d\u00fcrfen seit 4. Mai wieder Gottesdienste mit Beteiligung der Gl\u00e4ubigen gefeiert werden. Rund sieben Wochen waren \u00f6ffentliche Gottesdienste untersagt gewesen. Umso mehr freute sich Pfarrer Alfons Eder am Muttertagssonntag \u00fcber die rund 50 Gottesdienstbesucher [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-sdh.de\/side\/gottesdienst-mit-abstand\/\" \/>\n<meta property=\"og:site_name\" content=\"Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-10T11:49:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-13T08:09:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4962-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin Zangl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Zangl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/gottesdienst-mit-abstand\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/gottesdienst-mit-abstand\\\/\"},\"author\":{\"name\":\"Martin Zangl\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/e05baeb81583d4659c11ea77b24c3640\"},\"headline\":\"Gottesdienst mit Abstand\",\"datePublished\":\"2020-05-10T11:49:34+00:00\",\"dateModified\":\"2020-06-13T08:09:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/gottesdienst-mit-abstand\\\/\"},\"wordCount\":337,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/gottesdienst-mit-abstand\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/IMG_4962-scaled.jpg\",\"articleSection\":[\"Sch\u00f6nthal\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/gottesdienst-mit-abstand\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/gottesdienst-mit-abstand\\\/\",\"name\":\"Gottesdienst mit Abstand - Informationsseite und Seelsorgeeinheit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/gottesdienst-mit-abstand\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/gottesdienst-mit-abstand\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/IMG_4962-scaled.jpg\",\"datePublished\":\"2020-05-10T11:49:34+00:00\",\"dateModified\":\"2020-06-13T08:09:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/gottesdienst-mit-abstand\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/gottesdienst-mit-abstand\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/gottesdienst-mit-abstand\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/IMG_4962-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/IMG_4962-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/gottesdienst-mit-abstand\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gottesdienst mit Abstand\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"description\":\"Informationsseite und Seelsorgeeinheit\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"width\":438,\"height\":191,\"caption\":\"Informationsseite und Seelsorgeeinheit\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/e05baeb81583d4659c11ea77b24c3640\",\"name\":\"Martin Zangl\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/author\\\/zangl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gottesdienst mit Abstand - Informationsseite und Seelsorgeeinheit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-sdh.de\/side\/gottesdienst-mit-abstand\/","og_locale":"de_DE","og_type":"article","og_title":"Gottesdienst mit Abstand - Informationsseite und Seelsorgeeinheit","og_description":"Pfarrer Alfons Eder feiert erstmals wieder Gottesdienst mit Gl\u00e4ubigen &nbsp; &#8211; Unter Einhaltung der strengen Corona-Auflagen d\u00fcrfen seit 4. Mai wieder Gottesdienste mit Beteiligung der Gl\u00e4ubigen gefeiert werden. Rund sieben Wochen waren \u00f6ffentliche Gottesdienste untersagt gewesen. Umso mehr freute sich Pfarrer Alfons Eder am Muttertagssonntag \u00fcber die rund 50 Gottesdienstbesucher [&hellip;]","og_url":"https:\/\/www.kirche-sdh.de\/side\/gottesdienst-mit-abstand\/","og_site_name":"Informationsseite und Seelsorgeeinheit","article_published_time":"2020-05-10T11:49:34+00:00","article_modified_time":"2020-06-13T08:09:34+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4962-scaled.jpg","type":"image\/jpeg"}],"author":"Martin Zangl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Martin Zangl","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kirche-sdh.de\/side\/gottesdienst-mit-abstand\/#article","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/gottesdienst-mit-abstand\/"},"author":{"name":"Martin Zangl","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/e05baeb81583d4659c11ea77b24c3640"},"headline":"Gottesdienst mit Abstand","datePublished":"2020-05-10T11:49:34+00:00","dateModified":"2020-06-13T08:09:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/gottesdienst-mit-abstand\/"},"wordCount":337,"commentCount":0,"publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/gottesdienst-mit-abstand\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4962-scaled.jpg","articleSection":["Sch\u00f6nthal"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kirche-sdh.de\/side\/gottesdienst-mit-abstand\/","url":"https:\/\/www.kirche-sdh.de\/side\/gottesdienst-mit-abstand\/","name":"Gottesdienst mit Abstand - Informationsseite und Seelsorgeeinheit","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/gottesdienst-mit-abstand\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/gottesdienst-mit-abstand\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4962-scaled.jpg","datePublished":"2020-05-10T11:49:34+00:00","dateModified":"2020-06-13T08:09:34+00:00","breadcrumb":{"@id":"https:\/\/www.kirche-sdh.de\/side\/gottesdienst-mit-abstand\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-sdh.de\/side\/gottesdienst-mit-abstand\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/gottesdienst-mit-abstand\/#primaryimage","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4962-scaled.jpg","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/05\/IMG_4962-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-sdh.de\/side\/gottesdienst-mit-abstand\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-sdh.de\/side\/"},{"@type":"ListItem","position":2,"name":"Gottesdienst mit Abstand"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-sdh.de\/side\/#website","url":"https:\/\/www.kirche-sdh.de\/side\/","name":"Informationsseite und Seelsorgeeinheit","description":"Informationsseite und Seelsorgeeinheit","publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-sdh.de\/side\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.kirche-sdh.de\/side\/#organization","name":"Informationsseite und Seelsorgeeinheit","url":"https:\/\/www.kirche-sdh.de\/side\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","width":438,"height":191,"caption":"Informationsseite und Seelsorgeeinheit"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/e05baeb81583d4659c11ea77b24c3640","name":"Martin Zangl","url":"https:\/\/www.kirche-sdh.de\/side\/author\/zangl\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/12845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/comments?post=12845"}],"version-history":[{"count":0,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/12845\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media\/12846"}],"wp:attachment":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media?parent=12845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/categories?post=12845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/tags?post=12845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}