{"id":10943,"date":"2020-02-02T21:30:44","date_gmt":"2020-02-02T20:30:44","guid":{"rendered":"https:\/\/www.kirche-sdh.de\/side\/?p=10943"},"modified":"2020-02-02T21:30:44","modified_gmt":"2020-02-02T20:30:44","slug":"auf-die-fuersprache-des-heiligen-blasius","status":"publish","type":"post","link":"https:\/\/www.kirche-sdh.de\/side\/auf-die-fuersprache-des-heiligen-blasius\/","title":{"rendered":"Auf die F\u00fcrsprache des Heiligen Blasius"},"content":{"rendered":"<p>Als Kinder des Lichtes leben \u2013 Blasiussegen gespendet<\/p>\n<p><strong>Sch\u00f6nthal<\/strong>. Zum letzten Mal erleuchtete zum Vorabendgottesdienst am Fest \u201eDarstellung des Herrn\u201c oder fr\u00fcher als Mari\u00e4 Lichtmess bezeichnet der Christbaum die Sch\u00f6nthaler Pfarrkirche Sankt Michael. Gleichzeitig erf\u00fcllte Kerzenlicht das ansonsten dunkle Gotteshaus. Das warme und sch\u00f6ne Kerzenlicht symbolisiere das Lebenslicht, so Pfarrer Eder. Empfindsam und empfindlich, ein kleiner Windsto\u00df gen\u00fcge um das Kerzenlicht wie das Lebenslicht auszul\u00f6schen. Pfarrer Alfons Eder ging auf das Evangelium vom greisen Priester Simeon im Tempel von Jerusalem ein. Das Lebenslicht von Simeon und auch der anwesenden betagten Frau Hannah sei schon fast erloschen, doch brenne in ihren Herzen noch die Sehnsucht, den Messias zu sehen. Simeon erkennt in dem Kind Christus: \u201eMeine Augen haben das Heil gesehen, das Licht der Welt\u201c. Deshalb w\u00fcrden heute die Kerzen brennen. \u201eLassen wir uns erleuchten von diesem gl\u00e4ubigen Vertrauen, wir d\u00fcrfen als Kinder des Lichtes leben.\u201c ermunterte Pfarrer Eder die Gl\u00e4ubigen. Zusammen mit Diakon Alfons Eiber spendete er zum Abschluss des Gottesdienstes jedem Gottesdienstbesucher auf die F\u00fcrsprache des Heiligen Blasius den Segen \u201eDer allm\u00e4chtige Gott schenke dir Gesundheit und Heil.\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" class=\"aligncenter size-full wp-image-10944\" alt=\"\" src=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/02\/IMG_4556-scaled.jpg\" srcset=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/02\/IMG_4556-scaled.jpg 2560w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/02\/IMG_4556-300x200.jpg 300w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/02\/IMG_4556-1024x683.jpg 1024w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/02\/IMG_4556-768x512.jpg 768w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/02\/IMG_4556-1536x1024.jpg 1536w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/02\/IMG_4556-2048x1365.jpg 2048w, https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/02\/IMG_4556-360x240.jpg 360w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Als Kinder des Lichtes leben \u2013 Blasiussegen gespendet Sch\u00f6nthal. Zum letzten Mal erleuchtete zum Vorabendgottesdienst am Fest \u201eDarstellung des Herrn\u201c oder fr\u00fcher als Mari\u00e4 Lichtmess bezeichnet der Christbaum die Sch\u00f6nthaler Pfarrkirche Sankt Michael. Gleichzeitig erf\u00fcllte Kerzenlicht das ansonsten dunkle Gotteshaus. Das warme und sch\u00f6ne Kerzenlicht symbolisiere das Lebenslicht, so Pfarrer [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":10944,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-10943","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schoenthal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Auf die F\u00fcrsprache des Heiligen Blasius - Informationsseite und Seelsorgeeinheit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-sdh.de\/side\/auf-die-fuersprache-des-heiligen-blasius\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auf die F\u00fcrsprache des Heiligen Blasius - Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"og:description\" content=\"Als Kinder des Lichtes leben \u2013 Blasiussegen gespendet Sch\u00f6nthal. Zum letzten Mal erleuchtete zum Vorabendgottesdienst am Fest \u201eDarstellung des Herrn\u201c oder fr\u00fcher als Mari\u00e4 Lichtmess bezeichnet der Christbaum die Sch\u00f6nthaler Pfarrkirche Sankt Michael. Gleichzeitig erf\u00fcllte Kerzenlicht das ansonsten dunkle Gotteshaus. Das warme und sch\u00f6ne Kerzenlicht symbolisiere das Lebenslicht, so Pfarrer [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-sdh.de\/side\/auf-die-fuersprache-des-heiligen-blasius\/\" \/>\n<meta property=\"og:site_name\" content=\"Informationsseite und Seelsorgeeinheit\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-02T20:30:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/02\/IMG_4556-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin Zangl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Zangl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/auf-die-fuersprache-des-heiligen-blasius\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/auf-die-fuersprache-des-heiligen-blasius\\\/\"},\"author\":{\"name\":\"Martin Zangl\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/e05baeb81583d4659c11ea77b24c3640\"},\"headline\":\"Auf die F\u00fcrsprache des Heiligen Blasius\",\"datePublished\":\"2020-02-02T20:30:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/auf-die-fuersprache-des-heiligen-blasius\\\/\"},\"wordCount\":198,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/auf-die-fuersprache-des-heiligen-blasius\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG_4556-scaled.jpg\",\"articleSection\":[\"Sch\u00f6nthal\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/auf-die-fuersprache-des-heiligen-blasius\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/auf-die-fuersprache-des-heiligen-blasius\\\/\",\"name\":\"Auf die F\u00fcrsprache des Heiligen Blasius - Informationsseite und Seelsorgeeinheit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/auf-die-fuersprache-des-heiligen-blasius\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/auf-die-fuersprache-des-heiligen-blasius\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG_4556-scaled.jpg\",\"datePublished\":\"2020-02-02T20:30:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/auf-die-fuersprache-des-heiligen-blasius\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/auf-die-fuersprache-des-heiligen-blasius\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/auf-die-fuersprache-des-heiligen-blasius\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG_4556-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG_4556-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/auf-die-fuersprache-des-heiligen-blasius\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Auf die F\u00fcrsprache des Heiligen Blasius\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"description\":\"Informationsseite und Seelsorgeeinheit\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#organization\",\"name\":\"Informationsseite und Seelsorgeeinheit\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"contentUrl\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/kirche-logos.png\",\"width\":438,\"height\":191,\"caption\":\"Informationsseite und Seelsorgeeinheit\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/#\\\/schema\\\/person\\\/e05baeb81583d4659c11ea77b24c3640\",\"name\":\"Martin Zangl\",\"url\":\"https:\\\/\\\/www.kirche-sdh.de\\\/side\\\/author\\\/zangl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Auf die F\u00fcrsprache des Heiligen Blasius - Informationsseite und Seelsorgeeinheit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-sdh.de\/side\/auf-die-fuersprache-des-heiligen-blasius\/","og_locale":"de_DE","og_type":"article","og_title":"Auf die F\u00fcrsprache des Heiligen Blasius - Informationsseite und Seelsorgeeinheit","og_description":"Als Kinder des Lichtes leben \u2013 Blasiussegen gespendet Sch\u00f6nthal. Zum letzten Mal erleuchtete zum Vorabendgottesdienst am Fest \u201eDarstellung des Herrn\u201c oder fr\u00fcher als Mari\u00e4 Lichtmess bezeichnet der Christbaum die Sch\u00f6nthaler Pfarrkirche Sankt Michael. Gleichzeitig erf\u00fcllte Kerzenlicht das ansonsten dunkle Gotteshaus. Das warme und sch\u00f6ne Kerzenlicht symbolisiere das Lebenslicht, so Pfarrer [&hellip;]","og_url":"https:\/\/www.kirche-sdh.de\/side\/auf-die-fuersprache-des-heiligen-blasius\/","og_site_name":"Informationsseite und Seelsorgeeinheit","article_published_time":"2020-02-02T20:30:44+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/02\/IMG_4556-scaled.jpg","type":"image\/jpeg"}],"author":"Martin Zangl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Martin Zangl","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kirche-sdh.de\/side\/auf-die-fuersprache-des-heiligen-blasius\/#article","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/auf-die-fuersprache-des-heiligen-blasius\/"},"author":{"name":"Martin Zangl","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/e05baeb81583d4659c11ea77b24c3640"},"headline":"Auf die F\u00fcrsprache des Heiligen Blasius","datePublished":"2020-02-02T20:30:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/auf-die-fuersprache-des-heiligen-blasius\/"},"wordCount":198,"commentCount":0,"publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/auf-die-fuersprache-des-heiligen-blasius\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/02\/IMG_4556-scaled.jpg","articleSection":["Sch\u00f6nthal"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kirche-sdh.de\/side\/auf-die-fuersprache-des-heiligen-blasius\/","url":"https:\/\/www.kirche-sdh.de\/side\/auf-die-fuersprache-des-heiligen-blasius\/","name":"Auf die F\u00fcrsprache des Heiligen Blasius - Informationsseite und Seelsorgeeinheit","isPartOf":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-sdh.de\/side\/auf-die-fuersprache-des-heiligen-blasius\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/auf-die-fuersprache-des-heiligen-blasius\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/02\/IMG_4556-scaled.jpg","datePublished":"2020-02-02T20:30:44+00:00","breadcrumb":{"@id":"https:\/\/www.kirche-sdh.de\/side\/auf-die-fuersprache-des-heiligen-blasius\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-sdh.de\/side\/auf-die-fuersprache-des-heiligen-blasius\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/auf-die-fuersprache-des-heiligen-blasius\/#primaryimage","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/02\/IMG_4556-scaled.jpg","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2020\/02\/IMG_4556-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-sdh.de\/side\/auf-die-fuersprache-des-heiligen-blasius\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-sdh.de\/side\/"},{"@type":"ListItem","position":2,"name":"Auf die F\u00fcrsprache des Heiligen Blasius"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-sdh.de\/side\/#website","url":"https:\/\/www.kirche-sdh.de\/side\/","name":"Informationsseite und Seelsorgeeinheit","description":"Informationsseite und Seelsorgeeinheit","publisher":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-sdh.de\/side\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.kirche-sdh.de\/side\/#organization","name":"Informationsseite und Seelsorgeeinheit","url":"https:\/\/www.kirche-sdh.de\/side\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/","url":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","contentUrl":"https:\/\/www.kirche-sdh.de\/side\/wp-content\/uploads\/2017\/12\/kirche-logos.png","width":438,"height":191,"caption":"Informationsseite und Seelsorgeeinheit"},"image":{"@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.kirche-sdh.de\/side\/#\/schema\/person\/e05baeb81583d4659c11ea77b24c3640","name":"Martin Zangl","url":"https:\/\/www.kirche-sdh.de\/side\/author\/zangl\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/10943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/comments?post=10943"}],"version-history":[{"count":0,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/posts\/10943\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media\/10944"}],"wp:attachment":[{"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/media?parent=10943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/categories?post=10943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-sdh.de\/side\/wp-json\/wp\/v2\/tags?post=10943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}